{"id":1144,"date":"2026-07-10T06:22:01","date_gmt":"2026-07-10T06:22:01","guid":{"rendered":"https:\/\/isbm-blow-molding.com\/?p=1144"},"modified":"2026-07-10T06:22:01","modified_gmt":"2026-07-10T06:22:01","slug":"ibm-energy-consumption-hydraulic-vs-all-electric-zq60he-comparison","status":"publish","type":"post","link":"https:\/\/isbm-blow-molding.com\/pt\/ibm-energy-consumption-hydraulic-vs-all-electric-zq60he-comparison\/","title":{"rendered":"Consumo de energia da IBM: compara\u00e7\u00e3o entre o modelo hidr\u00e1ulico e o totalmente el\u00e9trico ZQ60HE"},"content":{"rendered":"<div style=\"margin: 0; padding: 0; font-family: 'Helvetica Neue',Helvetica,Arial,sans-serif; color: #1a2332; line-height: 1.78; background: #f0f3f7; overflow-x: hidden;\">\n<header style=\"position: relative; min-height: min(600px,88vh); display: flex; align-items: flex-end; width: 100%; background: #06090e; background-image: linear-gradient(155deg,rgba(6,9,14,0.97) 0%,rgba(10,14,22,0.83) 52%,rgba(16,24,36,0.50) 100%),url('https:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/07\/Injection-Blow-Molding-Machine-ZQ60.webp'); background-size: cover; background-position: center 40%;\">\n<div style=\"position: absolute; top: 0; left: 0; right: 0; height: 5px; background: linear-gradient(90deg,#d97706,#f59e0b,#d97706);\"><\/div>\n<div style=\"position: absolute; bottom: -1px; left: 0; right: 0; height: 56px; background: #f0f3f7; clip-path: polygon(0 100%,100% 100%,100% 0);\"><\/div>\n<div style=\"position: relative; z-index: 2; width: 100%; padding: clamp(48px,7vw,96px) clamp(20px,5vw,60px) clamp(52px,6vw,84px); box-sizing: border-box;\">\n<div style=\"display: inline-flex; align-items: center; gap: 8px; margin-bottom: 20px;\">\n<div style=\"width: 28px; height: 3px; background: #d97706;\"><\/div>\n<p><span style=\"font-size: 10px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #f59e0b;\">Consumo de energia da IBM \u00b7 Hidr\u00e1ulico vs. Totalmente el\u00e9trico \u00b7 S\u00e9rie ZQ da Korea EverPower<\/span><\/p>\n<div style=\"width: 28px; height: 3px; background: #d97706;\"><\/div>\n<\/div>\n<h1 style=\"font-size: clamp(26px,4.6vw,46px); font-weight: 900; color: #fff; line-height: 1.1; margin: 0 0 20px; letter-spacing: -0.8px; max-width: 740px;\">Consumo de energia da IBM:<br \/>\n<span style=\"color: #f59e0b;\">ZQ60HE hidr\u00e1ulico versus totalmente el\u00e9trico<\/span> Compara\u00e7\u00e3o<\/h1>\n<p style=\"font-size: clamp(14px,1.9vw,17px); color: #94a3b8; line-height: 1.7; margin: 0 0 30px; max-width: 640px;\">O custo de energia \u00e9 o segundo maior custo vari\u00e1vel de produ\u00e7\u00e3o na IBM, depois da resina polim\u00e9rica \u2014 e a diferen\u00e7a no consumo de energia entre as m\u00e1quinas IBM hidr\u00e1ulicas e totalmente el\u00e9tricas \u00e9 significativa o suficiente para afetar a viabilidade econ\u00f4mica do investimento em programas de produ\u00e7\u00e3o de 10 anos. Este guia apresenta dados de consumo de energia da s\u00e9rie ZQ da Korea Ever-Power para m\u00e1quinas IBM hidr\u00e1ulicas e para a m\u00e1quina IBM totalmente el\u00e9trica ZQ60HE, com compara\u00e7\u00e3o quantificada em kWh e an\u00e1lise da economia de custos de energia em 10 anos, considerando as tarifas de eletricidade coreanas e globais.<\/p>\n<div style=\"display: flex; flex-wrap: wrap; gap: 6px;\"><span style=\"background: rgba(217,119,6,0.15); border: 1px solid rgba(217,119,6,0.45); color: #fbbf24; font-size: 11px; font-weight: bold; padding: 4px 12px; border-radius: 2px; letter-spacing: 1px; text-transform: uppercase;\">~30% Economia de energia<\/span><br \/>\n<span style=\"background: rgba(255,255,255,0.06); border: 1px solid rgba(255,255,255,0.15); color: #94a3b8; font-size: 11px; font-weight: bold; padding: 4px 12px; border-radius: 2px; letter-spacing: 1px; text-transform: uppercase;\">Dados de kWh para todos os modelos ZQ<\/span><br \/>\n<span style=\"background: rgba(255,255,255,0.06); border: 1px solid rgba(255,255,255,0.15); color: #94a3b8; font-size: 11px; font-weight: bold; padding: 4px 12px; border-radius: 2px; letter-spacing: 1px; text-transform: uppercase;\">An\u00e1lise de custos de 10 anos<\/span><\/div>\n<p style=\"font-size: 11px; color: #475569; margin: 22px 0 0; letter-spacing: 1px;\">KOREA EVER-POWER \u00b7 ANSAN-SI, GYEONGGI-DO \u00b7 JULHO DE 2026<\/p>\n<\/div>\n<\/header>\n<p>&nbsp;<\/p>\n<div style=\"background: #0f1e35; border: 1px solid #1e3a5f; border-left: 4px solid #d97706; border-radius: 4px; padding: 24px 28px; margin: 52px 0 0;\">\n<div style=\"display: flex; align-items: center; gap: 10px; margin-bottom: 18px;\">\n<div style=\"width: 16px; height: 16px; border: 2px solid #d97706; border-radius: 50%; display: flex; align-items: center; justify-content: center; flex-shrink: 0;\">\n<div style=\"width: 6px; height: 6px; background: #d97706; border-radius: 50%;\"><\/div>\n<\/div>\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0;\">COMPARA\u00c7\u00c3O ENERG\u00c9TICA \u00b7 RESUMO DOS PRINCIPAIS DADOS<\/p>\n<\/div>\n<div style=\"display: grid; grid-template-columns: repeat(auto-fit,minmax(min(100%,170px),1fr)); gap: 1px; background: #1e3a5f;\">\n<div style=\"background: #0f1e35; padding: 16px 18px;\">\n<p style=\"font-size: 10px; font-weight: bold; letter-spacing: 2px; text-transform: uppercase; color: #475569; margin: 0 0 6px;\">Energia operacional do ZQ60HE<\/p>\n<p style=\"font-size: 20px; font-weight: 900; color: #f59e0b; margin: 0 0 4px;\">~12 kWh\/h<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">A energia operacional totalmente el\u00e9trica do ZQ60HE na produ\u00e7\u00e3o de PP IBM de 30 ml (105.000 a 115.000 frascos\/24h) \u2014 os servomotores consomem energia apenas durante a fase de atua\u00e7\u00e3o, e n\u00e3o continuamente como uma bomba hidr\u00e1ulica.<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 16px 18px;\">\n<p style=\"font-size: 10px; font-weight: bold; letter-spacing: 2px; text-transform: uppercase; color: #475569; margin: 0 0 6px;\">Energia Hidr\u00e1ulica ZQ60<\/p>\n<p style=\"font-size: 20px; font-weight: 900; color: #f59e0b; margin: 0 0 4px;\">18\u201322 kWh\/h<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">Energia operacional hidr\u00e1ulica ZQ60 equivalente a 30 ml PP na produ\u00e7\u00e3o IBM \u2014 a bomba hidr\u00e1ulica funciona continuamente a 18-22 kW, independentemente da fase do ciclo da m\u00e1quina, consumindo energia constante mesmo durante o tempo de resfriamento.<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 16px 18px;\">\n<p style=\"font-size: 10px; font-weight: bold; letter-spacing: 2px; text-transform: uppercase; color: #475569; margin: 0 0 6px;\">Economia de energia em 10 anos<\/p>\n<p style=\"font-size: 20px; font-weight: 900; color: #f59e0b; margin: 0 0 4px;\">KRW 52\u201386M<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">Compara\u00e7\u00e3o entre o sistema hidr\u00e1ulico ZQ60HE e o ZQ60: economia de custos de energia em 10 anos com eletricidade industrial coreana a KRW 120\/kWh, 16 horas\/dia e 300 dias\/ano de produ\u00e7\u00e3o \u2014 recuperando de 50 a 801 TP3T o pr\u00eamio de capital do ZQ60HE em rela\u00e7\u00e3o ao ZQ60 hidr\u00e1ulico.<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 16px 18px;\">\n<p style=\"font-size: 10px; font-weight: bold; letter-spacing: 2px; text-transform: uppercase; color: #475569; margin: 0 0 6px;\">Percentual de economia<\/p>\n<p style=\"font-size: 20px; font-weight: 900; color: #f59e0b; margin: 0 0 4px;\">~30-35%<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">Economia de energia do ZQ60HE em compara\u00e7\u00e3o com o ZQ60 hidr\u00e1ulico: consumo de energia aproximadamente 30-35% menor por hora em condi\u00e7\u00f5es de produ\u00e7\u00e3o equivalentes da IBM, consistente com os dados globais de vantagem energ\u00e9tica das m\u00e1quinas totalmente el\u00e9tricas da IBM.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<nav style=\"margin: 28px 0 0; background: #fff; border: 1px solid #cbd5e0; border-radius: 4px; padding: 22px 26px; position: relative; overflow: hidden;\">\n<div style=\"position: absolute; inset: 0; background-image: linear-gradient(rgba(30,58,95,0.03) 1px,transparent 1px),linear-gradient(90deg,rgba(30,58,95,0.03) 1px,transparent 1px); background-size: 24px 24px; pointer-events: none;\"><\/div>\n<div style=\"position: relative;\">\n<div style=\"display: flex; align-items: center; gap: 8px; margin-bottom: 14px;\">\n<div style=\"width: 3px; height: 14px; background: #d97706; border-radius: 2px;\"><\/div>\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 2.5px; text-transform: uppercase; color: #1e3a5f; margin: 0;\">\u00cdNDICE DE DOCUMENTOS<\/p>\n<\/div>\n<div style=\"display: grid; grid-template-columns: repeat(auto-fit,minmax(min(100%,270px),1fr)); gap: 2px 24px;\"><a style=\"color: #1e3a5f; text-decoration: none; font-size: 13.5px; padding: 4px 0; display: flex; align-items: baseline; border-bottom: 1px solid #f1f5f9;\" href=\"#s1\"><span style=\"color: #d97706; font-size: 10px; font-weight: 800; margin-right: 8px; flex-shrink: 0;\">01<\/span>Por que o consumo de energia da IBM \u00e9 importante para a economia do investimento em m\u00e1quinas<\/a><br \/>\n<a style=\"color: #1e3a5f; text-decoration: none; font-size: 13.5px; padding: 4px 0; display: flex; align-items: baseline; border-bottom: 1px solid #f1f5f9;\" href=\"#s2\"><span style=\"color: #d97706; font-size: 10px; font-weight: 800; margin-right: 8px; flex-shrink: 0;\">02<\/span>Perfil de Energia Hidr\u00e1ulica da IBM: Por que uma bomba hidr\u00e1ulica consome mais<\/a><br \/>\n<a style=\"color: #1e3a5f; text-decoration: none; font-size: 13.5px; padding: 4px 0; display: flex; align-items: baseline; border-bottom: 1px solid #f1f5f9;\" href=\"#s3\"><span style=\"color: #d97706; font-size: 10px; font-weight: 800; margin-right: 8px; flex-shrink: 0;\">03<\/span>Perfil de energia totalmente el\u00e9trica do ZQ60HE: Servoalimenta\u00e7\u00e3o sob demanda<\/a><br \/>\n<a style=\"color: #1e3a5f; text-decoration: none; font-size: 13.5px; padding: 4px 0; display: flex; align-items: baseline; border-bottom: 1px solid #f1f5f9;\" href=\"#s4\"><span style=\"color: #d97706; font-size: 10px; font-weight: 800; margin-right: 8px; flex-shrink: 0;\">04<\/span>Dados de consumo de energia: S\u00e9rie hidr\u00e1ulica ZQ vs ZQ60HE<\/a><br \/>\n<a style=\"color: #1e3a5f; text-decoration: none; font-size: 13.5px; padding: 4px 0; display: flex; align-items: baseline; border-bottom: 1px solid #f1f5f9;\" href=\"#s5\"><span style=\"color: #d97706; font-size: 10px; font-weight: 800; margin-right: 8px; flex-shrink: 0;\">05<\/span>An\u00e1lise de economia de custos de energia em 10 anos: mercados coreano e global<\/a><br \/>\n<a style=\"color: #1e3a5f; text-decoration: none; font-size: 13.5px; padding: 4px 0; display: flex; align-items: baseline; border-bottom: 1px solid #f1f5f9;\" href=\"#s6\"><span style=\"color: #d97706; font-size: 10px; font-weight: 800; margin-right: 8px; flex-shrink: 0;\">06<\/span>Redu\u00e7\u00e3o da pegada de carbono: o posicionamento de sustentabilidade da IBM<\/a><br \/>\n<a style=\"color: #1e3a5f; text-decoration: none; font-size: 13.5px; padding: 4px 0; display: flex; align-items: baseline;\" href=\"#faq\"><span style=\"color: #d97706; font-size: 10px; font-weight: 800; margin-right: 8px; flex-shrink: 0;\">Perguntas frequentes<\/span>Quest\u00f5es de Engenharia sobre Consumo de Energia da IBM<\/a><\/div>\n<\/div>\n<\/nav>\n<div style=\"padding: 0px 2%;\">\n<section id=\"s1\" style=\"margin: 64px 0 0;\">\n<div style=\"display: flex; align-items: stretch; gap: 0; margin-bottom: 22px;\">\n<div style=\"width: 4px; background: linear-gradient(180deg,#d97706,#f59e0b); border-radius: 2px; flex-shrink: 0;\"><\/div>\n<div style=\"padding: 10px 16px; background: #fff; border: 1px solid #e2e8f0; border-left: none; flex: 1;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 3px;\">SE\u00c7\u00c3O 01<\/p>\n<h2 style=\"font-size: clamp(17px,2.4vw,22px); font-weight: 800; color: #0f1e35; margin: 0; line-height: 1.2;\">Por que o consumo de energia da IBM \u00e9 importante para a economia do investimento em m\u00e1quinas<\/h2>\n<\/div>\n<\/div>\n<p style=\"font-size: 16px; margin-bottom: 20px;\">O custo de energia \u00e9 o segundo maior custo vari\u00e1vel de produ\u00e7\u00e3o na fabrica\u00e7\u00e3o de embalagens IBM, depois da resina polim\u00e9rica. Para programas IBM de alto volume na Coreia, com opera\u00e7\u00e3o de 16 horas\/dia durante 300 dias\/ano, a diferen\u00e7a no custo de energia entre m\u00e1quinas IBM hidr\u00e1ulicas e totalmente el\u00e9tricas se acumula, resultando em um valor comercialmente significativo ao longo de uma vida \u00fatil de 10 anos. Compreender o consumo de energia das m\u00e1quinas IBM permite que os compradores coreanos incluam o custo de energia de 10 anos na compara\u00e7\u00e3o do custo total de propriedade (TCO) entre os modelos ZQ40, ZQ60, ZQ80, ZQ110 e ZQ135 (hidr\u00e1ulicos) e o modelo ZQ60HE (totalmente el\u00e9trico) \u2014 e tomem uma decis\u00e3o de sele\u00e7\u00e3o de m\u00e1quina com base em uma an\u00e1lise econ\u00f4mica completa, e n\u00e3o apenas no custo de capital. Os dados de energia da s\u00e9rie ZQ da Korea Ever-Power apresentados neste guia s\u00e3o baseados na pot\u00eancia operacional medida na f\u00e1brica da Korea Ever-Power em Ansan-si, sob condi\u00e7\u00f5es padr\u00e3o de produ\u00e7\u00e3o IBM na Coreia: IBM com homopol\u00edmero de PP, formato de garrafa de 100 ml, 10 cavidades, produ\u00e7\u00e3o em dois turnos na Coreia, com temperatura ambiente de 20 a 25 \u00b0C. Clientes globais devem aplicar suas tarifas de eletricidade locais e as condi\u00e7\u00f5es ambientais de produ\u00e7\u00e3o aos dados de energia fornecidos para um c\u00e1lculo preciso do custo de energia local. <a style=\"color: #1e3a5f; font-weight: 600; text-decoration: none;\" href=\"https:\/\/isbm-blow-molding.com\/pt\/product-category\/injection-blow-molding-machine\/\">Linha de m\u00e1quinas IBM Ever-Power da Coreia<\/a> Os modelos ZQ40 a ZQ60HE est\u00e3o dispon\u00edveis com documenta\u00e7\u00e3o de consumo de energia para an\u00e1lise de investimento de clientes coreanos.<\/p>\n<p>&nbsp;<\/p>\n<figure style=\"margin: 0 0 24px;\"><img decoding=\"async\" style=\"width: 100%; height: auto; border-radius: 3px; display: block; border: 1px solid #cbd5e0;\" title=\"IBM Energy Consumption ZQ Series Hydraulic vs ZQ60HE Korea Ever-Power\" src=\"https:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/07\/IBM-PRODUCTION-LINE-COMPONENTS.webp\" alt=\"Korea Ever-Power ZQ series IBM production line energy consumption hydraulic vs all-electric ZQ60HE comparison kWh per hour PP IBM production Korea Ever-Power\" \/><figcaption style=\"font-size: 12px; color: #64748b; margin-top: 8px; padding-left: 10px; border-left: 2px solid #d97706;\">Linha de produ\u00e7\u00e3o ZQ IBM da Korea Ever-Power \u2014 o consumo de energia do sistema de produ\u00e7\u00e3o IBM compreende a energia das m\u00e1quinas IBM (componente dominante, representando 65-751 TP3T do total), a energia do chiller de resfriamento do molde (15-201 TP3T), a energia da tremonha de secagem de material (5-81 TP3T) e a energia dos transportadores\/equipamentos auxiliares (3-51 TP3T). Este guia concentra-se no consumo de energia das m\u00e1quinas IBM (o componente control\u00e1vel \u00e9 determinado pelo tipo de m\u00e1quina \u2014 hidr\u00e1ulica versus totalmente el\u00e9trica ZQ60HE) e fornece estimativas do consumo total de energia do sistema de produ\u00e7\u00e3o IBM, onde os dados de consumo auxiliar est\u00e3o dispon\u00edveis no sistema de monitoramento de produ\u00e7\u00e3o Ansan-si da Korea Ever-Power.<\/figcaption><\/figure>\n<\/section>\n<section id=\"s2\" style=\"margin: 56px 0 0;\">\n<div style=\"display: flex; align-items: stretch; gap: 0; margin-bottom: 22px;\">\n<div style=\"width: 4px; background: linear-gradient(180deg,#d97706,#f59e0b); border-radius: 2px; flex-shrink: 0;\"><\/div>\n<div style=\"padding: 10px 16px; background: #fff; border: 1px solid #e2e8f0; border-left: none; flex: 1;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 3px;\">SE\u00c7\u00c3O 02<\/p>\n<h2 style=\"font-size: clamp(17px,2.4vw,22px); font-weight: 800; color: #0f1e35; margin: 0; line-height: 1.2;\">Perfil de Energia Hidr\u00e1ulica da IBM: Por que uma bomba hidr\u00e1ulica consome mais<\/h2>\n<\/div>\n<\/div>\n<div style=\"display: grid; grid-template-columns: repeat(auto-fit,minmax(min(100%,260px),1fr)); gap: 14px; margin: 0 0 22px;\">\n<div style=\"background: #fff; border: 1px solid #e2e8f0; border-top: 3px solid #d97706; border-radius: 4px; padding: 16px 18px;\">\n<p style=\"font-size: 10px; font-weight: 800; letter-spacing: 2px; text-transform: uppercase; color: #d97706; margin: 0 0 10px;\">Opera\u00e7\u00e3o cont\u00ednua da bomba<\/p>\n<p style=\"font-size: 14px; color: #374151; margin: 0; line-height: 1.65;\">As m\u00e1quinas hidr\u00e1ulicas IBM (ZQ40, ZQ60, ZQ80, ZQ110, ZQ135) utilizam uma bomba hidr\u00e1ulica de deslocamento fixo ou vari\u00e1vel acionada continuamente por um motor el\u00e9trico que opera em velocidade nominal durante todo o turno de produ\u00e7\u00e3o. O motor da bomba hidr\u00e1ulica opera com pot\u00eancia nominal m\u00e1xima tanto durante as fases ativas do ciclo da m\u00e1quina (inje\u00e7\u00e3o, fechamento, sopro) quanto durante o tempo de resfriamento \u2014 embora o tempo de resfriamento (55-70 TP3T do tempo total do ciclo IBM) n\u00e3o exija acionamento hidr\u00e1ulico. Durante o tempo de resfriamento, o motor da bomba hidr\u00e1ulica descarrega contra o acumulador hidr\u00e1ulico, mas continua consumindo de 30 a 50 TP3T de pot\u00eancia de plena carga (o consumo de energia da bomba em vazio devido \u00e0s perdas de circula\u00e7\u00e3o do fluido hidr\u00e1ulico e ao atrito mec\u00e2nico da bomba). Esse consumo cont\u00ednuo de energia em vazio durante o tempo de resfriamento do ciclo IBM \u00e9 o principal motivo pelo qual as m\u00e1quinas hidr\u00e1ulicas IBM consomem de 30 a 35 TP3T a mais de energia do que as m\u00e1quinas servo el\u00e9tricas IBM em condi\u00e7\u00f5es de produ\u00e7\u00e3o equivalentes.<\/p>\n<\/div>\n<div style=\"background: #fff; border: 1px solid #e2e8f0; border-top: 3px solid #1e3a5f; border-radius: 4px; padding: 16px 18px;\">\n<p style=\"font-size: 10px; font-weight: 800; letter-spacing: 2px; text-transform: uppercase; color: #1e3a5f; margin: 0 0 10px;\">Gera\u00e7\u00e3o de calor em sistema hidr\u00e1ulico<\/p>\n<p style=\"font-size: 14px; color: #374151; margin: 0; line-height: 1.65;\">Os sistemas hidr\u00e1ulicos das m\u00e1quinas IBM geram calor significativo devido ao atrito viscoso do fluido hidr\u00e1ulico, \u00e0 inefici\u00eancia da bomba e \u00e0s quedas de press\u00e3o nas v\u00e1lvulas hidr\u00e1ulicas. O sistema hidr\u00e1ulico ZQ60 gera aproximadamente 3 a 5 kW de calor residual no reservat\u00f3rio de \u00f3leo hidr\u00e1ulico durante a opera\u00e7\u00e3o cont\u00ednua de produ\u00e7\u00e3o \u2014 exigindo resfriamento ativo do \u00f3leo hidr\u00e1ulico (resfriador de \u00f3leo separado ou circuito de resfriamento a \u00e1gua para o tanque de \u00f3leo hidr\u00e1ulico), o que adiciona de 0,5 a 1,5 kW de energia de resfriamento ao consumo de energia do sistema hidr\u00e1ulico ZQ60. Essa gera\u00e7\u00e3o de calor hidr\u00e1ulico eleva a temperatura ambiente da f\u00e1brica ao redor da m\u00e1quina IBM, aumentando a carga de resfriamento do ambiente de produ\u00e7\u00e3o da IBM no sistema HVAC da f\u00e1brica coreana \u2014 um custo indireto de energia que normalmente n\u00e3o \u00e9 inclu\u00eddo nas compara\u00e7\u00f5es de consumo de energia das m\u00e1quinas IBM, mas representa uma desvantagem energ\u00e9tica adicional e oculta da IBM hidr\u00e1ulica em compara\u00e7\u00e3o com a ZQ60HE totalmente el\u00e9trica.<\/p>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"s3\" style=\"margin: 56px 0 0;\">\n<div style=\"display: flex; align-items: stretch; gap: 0; margin-bottom: 22px;\">\n<div style=\"width: 4px; background: linear-gradient(180deg,#d97706,#f59e0b); border-radius: 2px; flex-shrink: 0;\"><\/div>\n<div style=\"padding: 10px 16px; background: #fff; border: 1px solid #e2e8f0; border-left: none; flex: 1;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 3px;\">SE\u00c7\u00c3O 03<\/p>\n<h2 style=\"font-size: clamp(17px,2.4vw,22px); font-weight: 800; color: #0f1e35; margin: 0; line-height: 1.2;\">Perfil de energia totalmente el\u00e9trica do ZQ60HE: Servoalimenta\u00e7\u00e3o sob demanda<\/h2>\n<\/div>\n<\/div>\n<figure style=\"margin: 0 0 24px;\"><img decoding=\"async\" style=\"width: 100%; height: auto; border-radius: 3px; display: block; border: 1px solid #cbd5e0;\" title=\"ZQ60HE All-Electric IBM Energy Profile On-Demand Servo Power Korea Ever-Power\" src=\"https:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/07\/IBM-Internal-structure.webp\" alt=\"Korea Ever-Power ZQ60HE all-electric IBM servo motor drives energy profile on-demand power consumption versus hydraulic continuous pump energy comparison IBM production\" \/><figcaption style=\"font-size: 12px; color: #64748b; margin-top: 8px; padding-left: 10px; border-left: 2px solid #d97706;\">A arquitetura de acionamento interno por servomotores IBM totalmente el\u00e9trica da ZQ60HE permite que cada servomotor (inje\u00e7\u00e3o 22 kW, alimenta\u00e7\u00e3o por parafuso 18 kW, fechamento 15+15 kW, rotativo 2,9 kW) consuma energia apenas durante sua fase de atua\u00e7\u00e3o espec\u00edfica no ciclo IBM. Durante a parada de resfriamento PP IBM (a fase mais longa do ciclo IBM, em 55-70% do ciclo total), todos os servomotores ficam parados e consomem energia pr\u00f3xima de zero (corrente de espera do servomotor &lt;0,5 A por servomotor). Esse perfil de energia sob demanda \u00e9 o mecanismo fundamental da vantagem energ\u00e9tica da ZQ60HE em rela\u00e7\u00e3o \u00e0s m\u00e1quinas IBM hidr\u00e1ulicas em condi\u00e7\u00f5es de produ\u00e7\u00e3o equivalentes.<\/figcaption><\/figure>\n<div style=\"background: #0f1e35; border-radius: 4px; padding: 18px 22px; border-top: 3px solid #d97706; margin: 0 0 22px;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 14px;\">Consumo de energia do ZQ60HE por fase do ciclo IBM (refer\u00eancia IBM de 100 ml PP)<\/p>\n<div style=\"display: grid; grid-template-columns: repeat(auto-fit,minmax(min(100%,185px),1fr)); gap: 1px; background: #1e3a5f;\">\n<div style=\"background: #0f1e35; padding: 12px 14px;\">\n<p style=\"font-size: 10px; color: #f59e0b; font-weight: bold; margin: 0 0 5px; letter-spacing: 1px; text-transform: uppercase;\">Fase de Inje\u00e7\u00e3o (0,8s)<\/p>\n<p style=\"font-size: 15px; font-weight: 900; color: #f59e0b; margin: 0 0 3px;\">Pot\u00eancia de pico de aproximadamente 35-45 kW<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">Servo injetor operando em pot\u00eancia nominal m\u00e1xima durante o curso de enchimento de 0,8 s com inje\u00e7\u00e3o de PP. Pot\u00eancia m\u00e1xima de 35-45 kW proveniente do servo injetor (22 kW) + alimenta\u00e7\u00e3o por parafuso (18 kW) + reten\u00e7\u00e3o da mesa rotativa (2,9 kW). Dura\u00e7\u00e3o do ciclo total: 20%.<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 12px 14px;\">\n<p style=\"font-size: 10px; color: #f59e0b; font-weight: bold; margin: 0 0 5px; letter-spacing: 1px; text-transform: uppercase;\">Fixa\u00e7\u00e3o + Sopro (0,7s)<\/p>\n<p style=\"font-size: 15px; font-weight: 900; color: #f59e0b; margin: 0 0 3px;\">~25-35 kW<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">Servos de fechamento (15+15 kW) durante o fechamento do molde + manuten\u00e7\u00e3o da press\u00e3o de sopro. Servo de inje\u00e7\u00e3o retra\u00eddo (tra\u00e7\u00e3o pr\u00f3xima de zero). Dura\u00e7\u00e3o do ciclo total: 17%.<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 12px 14px;\">\n<p style=\"font-size: 10px; color: #f59e0b; font-weight: bold; margin: 0 0 5px; letter-spacing: 1px; text-transform: uppercase;\">Tempo de espera de resfriamento (2,5s)<\/p>\n<p style=\"font-size: 15px; font-weight: 900; color: #f59e0b; margin: 0 0 3px;\">~3-5 kW<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">Consumo de energia do servomotor pr\u00f3ximo de zero durante o per\u00edodo de resfriamento do PP \u2014 apenas energia do aquecedor do cilindro (2-3 kW) e corrente de espera do servo (&lt;0,5 A por acionamento). Dura\u00e7\u00e3o do ciclo total de 63% = economia de energia prim\u00e1ria em compara\u00e7\u00e3o com o sistema hidr\u00e1ulico IBM.<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 12px 14px;\">\n<p style=\"font-size: 10px; color: #f59e0b; font-weight: bold; margin: 0 0 5px; letter-spacing: 1px; text-transform: uppercase;\">Rotativo + Tira (0,4s)<\/p>\n<p style=\"font-size: 15px; font-weight: 900; color: #f59e0b; margin: 0 0 3px;\">~8-12 kW<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">Servo da mesa rotativa (2,9 kW) + servo de remo\u00e7\u00e3o (movimento reverso do servo de fixa\u00e7\u00e3o) durante a rota\u00e7\u00e3o da mesa e remo\u00e7\u00e3o das garrafas. Dura\u00e7\u00e3o aproximada de 10% do ciclo total.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"s4\" style=\"margin: 56px 0 0;\">\n<div style=\"display: flex; align-items: stretch; gap: 0; margin-bottom: 22px;\">\n<div style=\"width: 4px; background: linear-gradient(180deg,#d97706,#f59e0b); border-radius: 2px; flex-shrink: 0;\"><\/div>\n<div style=\"padding: 10px 16px; background: #fff; border: 1px solid #e2e8f0; border-left: none; flex: 1;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 3px;\">SE\u00c7\u00c3O 04<\/p>\n<h2 style=\"font-size: clamp(17px,2.4vw,22px); font-weight: 800; color: #0f1e35; margin: 0; line-height: 1.2;\">Dados de consumo de energia: S\u00e9rie hidr\u00e1ulica ZQ vs ZQ60HE<\/h2>\n<\/div>\n<\/div>\n<div style=\"overflow-x: auto; margin: 0 0 22px;\">\n<table style=\"width: 100%; border-collapse: collapse; font-size: 13px; min-width: 540px;\">\n<thead>\n<tr style=\"background: #0f1e35;\">\n<th style=\"color: #f59e0b; padding: 10px 12px; text-align: left; font-weight: bold; border-right: 1px solid #1e3a5f;\">M\u00c1QUINA<\/th>\n<th style=\"color: #f59e0b; padding: 10px 10px; text-align: center; font-weight: bold; border-right: 1px solid #1e3a5f;\">TIPO<\/th>\n<th style=\"color: #f59e0b; padding: 10px 10px; text-align: center; font-weight: bold; border-right: 1px solid #1e3a5f;\">INSTALADO (kW)<\/th>\n<th style=\"color: #f59e0b; padding: 10px 10px; text-align: center; font-weight: bold; border-right: 1px solid #1e3a5f;\">OPERACIONAL (kWh\/h)<\/th>\n<th style=\"color: #f59e0b; padding: 10px 10px; text-align: center; font-weight: bold;\">DI\u00c1RIO (16h, kWh)<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr style=\"background: #fff;\">\n<td style=\"padding: 9px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: bold; color: #d97706;\">ZQ40<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center;\">Hidr\u00e1ulico<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center;\">22<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center; font-weight: bold;\">8\u201312<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; text-align: center;\">128\u2013192<\/td>\n<\/tr>\n<tr style=\"background: #f8fafc;\">\n<td style=\"padding: 9px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: bold; color: #d97706;\">ZQ60<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center;\">Hidr\u00e1ulico<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center;\">30<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center; font-weight: bold;\">18\u201322<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; text-align: center;\">288\u2013352<\/td>\n<\/tr>\n<tr style=\"background: #fff9ec; border: 1px solid #fde68a;\">\n<td style=\"padding: 9px 12px; border-bottom: 1px solid #fde68a; border-right: 1px solid #fde68a; font-weight: bold; color: #d97706;\">ZQ60HE \u2605<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #fde68a; border-right: 1px solid #fde68a; text-align: center; font-weight: bold; color: #d97706;\">Totalmente el\u00e9trico<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #fde68a; border-right: 1px solid #fde68a; text-align: center;\">90 (instalado)<br \/>\n<span style=\"font-size: 11px; color: #64748b;\">15-25 em opera\u00e7\u00e3o<\/span><\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #fde68a; border-right: 1px solid #fde68a; text-align: center; font-weight: bold; color: #059669;\">12\u201315<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #fde68a; text-align: center; font-weight: bold; color: #059669;\">192\u2013240<\/td>\n<\/tr>\n<tr style=\"background: #fff;\">\n<td style=\"padding: 9px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: bold; color: #d97706;\">ZQ80<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center;\">Hidr\u00e1ulico<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center;\">45<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center; font-weight: bold;\">25\u201332<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; text-align: center;\">400\u2013512<\/td>\n<\/tr>\n<tr style=\"background: #f8fafc;\">\n<td style=\"padding: 9px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: bold; color: #d97706;\">ZQ110<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center;\">Hidr\u00e1ulico<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center;\">60<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center; font-weight: bold;\">35\u201345<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; text-align: center;\">560\u2013720<\/td>\n<\/tr>\n<tr style=\"background: #fff;\">\n<td style=\"padding: 9px 12px; border-right: 1px solid #e2e8f0; font-weight: bold; color: #d97706;\">ZQ135<\/td>\n<td style=\"padding: 9px 10px; border-right: 1px solid #e2e8f0; text-align: center;\">Hidr\u00e1ulico<\/td>\n<td style=\"padding: 9px 10px; border-right: 1px solid #e2e8f0; text-align: center;\">75<\/td>\n<td style=\"padding: 9px 10px; border-right: 1px solid #e2e8f0; text-align: center; font-weight: bold;\">40\u201355<\/td>\n<td style=\"padding: 9px 10px; text-align: center;\">640\u2013880<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div style=\"background: #fff; border: 1px solid #e2e8f0; border-left: 4px solid #059669; padding: 12px 18px; border-radius: 0 4px 4px 0;\">\n<p style=\"font-size: 13px; color: #374151; margin: 0; line-height: 1.65;\"><strong style=\"color: #059669;\">Nota sobre pot\u00eancia instalada versus pot\u00eancia operacional:<\/strong> A capacidade instalada do ZQ60HE \u00e9 de 90 kW (soma das pot\u00eancias nominais de todos os servomotores), mas a pot\u00eancia operacional na produ\u00e7\u00e3o da IBM \u00e9 de apenas 12-15 kWh\/h, pois os servomotores operam em breves pulsos de atua\u00e7\u00e3o de alta pot\u00eancia (0,5-0,8 s) com consumo pr\u00f3ximo de zero durante o per\u00edodo de resfriamento de 2-3 s entre os pulsos. Os clientes coreanos devem usar a pot\u00eancia operacional (12-15 kWh\/h) para o c\u00e1lculo do custo de energia, e n\u00e3o a capacidade instalada.<\/p>\n<\/div>\n<\/section>\n<figure style=\"margin: 0 0 24px;\"><img decoding=\"async\" style=\"width: 100%; height: auto; border-radius: 3px; display: block; border: 1px solid #cbd5e0;\" title=\"ZQ60HE Energy Efficient IBM Output Korea Ever-Power\" src=\"https:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/07\/Typles-0f-Bottle-1.webp\" alt=\"PP IBM container output Korea Ever-Power ZQ60HE all-electric energy efficient IBM production 30% lower kWh versus hydraulic ZQ60 cosmetic pharmaceutical bottles\" \/><figcaption style=\"font-size: 12px; color: #64748b; margin-top: 8px; padding-left: 10px; border-left: 2px solid #d97706;\">A produ\u00e7\u00e3o de embalagens PP IBM da m\u00e1quina totalmente el\u00e9trica ZQ60HE da Korea Ever-Power apresenta um consumo de energia aproximadamente 53% menor por embalagem em compara\u00e7\u00e3o com a ZQ60 hidr\u00e1ulica (que combina um consumo de energia hor\u00e1ria 30-35% menor e uma produ\u00e7\u00e3o de embalagens 20-25% maior por hora, gra\u00e7as ao ciclo de secagem de 2,5 segundos da ZQ60HE). Dessa forma, a ZQ60HE produz essas embalagens PP IBM para cosm\u00e9ticos e produtos farmac\u00eauticos com o menor custo de energia por embalagem da linha de m\u00e1quinas ZQ da Korea Ever-Power. Clientes coreanos de marcas de cosm\u00e9ticos e produtos farmac\u00eauticos que utilizam embalagens IBM produzidas pela ZQ60HE podem comprovar a redu\u00e7\u00e3o de energia por embalagem em seus relat\u00f3rios ESG e em suas comunica\u00e7\u00f5es sobre embalagens ecol\u00f3gicas, em conformidade com as normas da Comiss\u00e3o Coreana de Com\u00e9rcio Justo.<\/figcaption><\/figure>\n<section id=\"s5\" style=\"margin: 56px 0 0;\">\n<div style=\"display: flex; align-items: stretch; gap: 0; margin-bottom: 22px;\">\n<div style=\"width: 4px; background: linear-gradient(180deg,#d97706,#f59e0b); border-radius: 2px; flex-shrink: 0;\"><\/div>\n<div style=\"padding: 10px 16px; background: #fff; border: 1px solid #e2e8f0; border-left: none; flex: 1;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 3px;\">SE\u00c7\u00c3O 05<\/p>\n<h2 style=\"font-size: clamp(17px,2.4vw,22px); font-weight: 800; color: #0f1e35; margin: 0; line-height: 1.2;\">An\u00e1lise de economia de custos de energia em 10 anos: mercados coreano e global<\/h2>\n<\/div>\n<\/div>\n<div style=\"background: #0f1e35; border-radius: 4px; padding: 18px 22px; border-top: 3px solid #d97706; margin: 0 0 22px;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 14px;\">ZQ60HE vs ZQ60 HIDR\u00c1ULICO \u2014 ECONOMIA DE ENERGIA DE 10 ANOS (BASE: 16 HORAS\/DIA, 300 DIAS\/ANO)<\/p>\n<div style=\"display: grid; grid-template-columns: repeat(auto-fit,minmax(min(100%,200px),1fr)); gap: 1px; background: #1e3a5f;\">\n<div style=\"background: #0f1e35; padding: 12px 14px;\">\n<p style=\"font-size: 10px; color: #f59e0b; font-weight: bold; margin: 0 0 5px; letter-spacing: 1px; text-transform: uppercase;\">Economia anual (kWh)<\/p>\n<p style=\"font-size: 15px; font-weight: 900; color: #f59e0b; margin: 0 0 3px;\">86.400\u2013115.200<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">Economia de energia: (18-22 kWh\/h ZQ60) menos (12-15 kWh\/h ZQ60HE) = economia de 6-10 kWh\/h \u00d7 16 h\/dia \u00d7 300 dias = 28.800-48.000 kWh\/ano. A faixa reflete a varia\u00e7\u00e3o da carga hidr\u00e1ulica do ZQ60 em diferentes formatos PP IBM.<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 12px 14px;\">\n<p style=\"font-size: 10px; color: #f59e0b; font-weight: bold; margin: 0 0 5px; letter-spacing: 1px; text-transform: uppercase;\">Poupan\u00e7a anual (KRW coreano)<\/p>\n<p style=\"font-size: 15px; font-weight: 900; color: #f59e0b; margin: 0 0 3px;\">KRW 3,5\u20135,8 milh\u00f5es<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">Consumo de eletricidade industrial coreana a KRW 120\/kWh (tarifa de 2026): 28.800-48.000 kWh\/ano \u00d7 KRW 120 = KRW 3,46-5,76 milh\u00f5es. Economia anual de energia por ZQ60HE em compara\u00e7\u00e3o com ZQ60 hidr\u00e1ulico no mesmo programa de produ\u00e7\u00e3o.<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 12px 14px;\">\n<p style=\"font-size: 10px; color: #f59e0b; font-weight: bold; margin: 0 0 5px; letter-spacing: 1px; text-transform: uppercase;\">Poupan\u00e7a de 10 anos (Coreia)<\/p>\n<p style=\"font-size: 15px; font-weight: 900; color: #f59e0b; margin: 0 0 3px;\">KRW 35\u201358M<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">Economia de energia acumulada em 10 anos com base na tarifa de eletricidade coreana (antes do ajuste de escalonamento tarif\u00e1rio) \u2014 representando 50-80% de pr\u00eamio de capital do ZQ60HE em rela\u00e7\u00e3o ao ZQ60 hidr\u00e1ulico, recuperado apenas por meio da economia de energia.<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 12px 14px;\">\n<p style=\"font-size: 10px; color: #f59e0b; font-weight: bold; margin: 0 0 5px; letter-spacing: 1px; text-transform: uppercase;\">Poupan\u00e7a anual (\u00cdndia INR)<\/p>\n<p style=\"font-size: 15px; font-weight: 900; color: #f59e0b; margin: 0 0 3px;\">INR 245.000\u2013410.000<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">Consumo m\u00e9dio de eletricidade industrial na \u00cdndia: INR 8,5\/kWh: 28.800-48.000 kWh\/ano \u00d7 INR 8,5 = INR 245.000-408.000 de economia de energia anual com o ZQ60HE para clientes da IBM na \u00cdndia.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"s6\" style=\"margin: 56px 0 0;\">\n<div style=\"display: flex; align-items: stretch; gap: 0; margin-bottom: 22px;\">\n<div style=\"width: 4px; background: linear-gradient(180deg,#d97706,#f59e0b); border-radius: 2px; flex-shrink: 0;\"><\/div>\n<div style=\"padding: 10px 16px; background: #fff; border: 1px solid #e2e8f0; border-left: none; flex: 1;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 3px;\">SE\u00c7\u00c3O 06<\/p>\n<h2 style=\"font-size: clamp(17px,2.4vw,22px); font-weight: 800; color: #0f1e35; margin: 0; line-height: 1.2;\">Redu\u00e7\u00e3o da pegada de carbono: o posicionamento de sustentabilidade da IBM<\/h2>\n<\/div>\n<\/div>\n<div style=\"display: grid; grid-template-columns: repeat(auto-fit,minmax(min(100%,260px),1fr)); gap: 14px; margin: 0 0 22px;\">\n<div style=\"background: #fff; border: 1px solid #e2e8f0; border-top: 3px solid #d97706; border-radius: 4px; padding: 16px 18px;\">\n<p style=\"font-size: 10px; font-weight: 800; letter-spacing: 2px; text-transform: uppercase; color: #d97706; margin: 0 0 10px;\">Redu\u00e7\u00e3o anual de CO\u2082 do ZQ60HE<\/p>\n<p style=\"font-size: 14px; color: #374151; margin: 0; line-height: 1.65;\">A economia de energia do ZQ60HE de 28.800 a 48.000 kWh\/ano em compara\u00e7\u00e3o com o ZQ60 hidr\u00e1ulico se traduz em uma redu\u00e7\u00e3o anual de emiss\u00f5es de CO\u2082 considerando o fator de emiss\u00e3o da rede el\u00e9trica coreana de 0,4578 kgCO\u2082\/kWh (fator de emiss\u00e3o da rede da Korea Electric Power Corporation para 2024): 28.800 a 48.000 kWh\/ano \u00d7 0,4578 kg CO\u2082\/kWh = redu\u00e7\u00e3o anual de 13,2 a 22,0 toneladas de CO\u2082 por ZQ60HE em compara\u00e7\u00e3o com o ZQ60 hidr\u00e1ulico. Ao longo de 10 anos: redu\u00e7\u00e3o cumulativa de 132 a 220 toneladas de CO\u2082 por m\u00e1quina IBM com ZQ60HE \u2014 equivalente a aproximadamente 55 a 90 anos-carro de passeio em termos de emiss\u00f5es de CO\u2082. Para os fabricantes coreanos de cont\u00eaineres IBM que participam do mercado de cr\u00e9ditos de carbono K-ETS (Korean Emissions Trading Scheme), a economia de energia do ZQ60HE gera uma redu\u00e7\u00e3o mensur\u00e1vel nas emiss\u00f5es de GEE (gases de efeito estufa) que pode ser contabilizada na aloca\u00e7\u00e3o de carbono da ind\u00fastria coreana ou vendida como cr\u00e9ditos de carbono ao pre\u00e7o de mercado do K-ETS.<\/p>\n<\/div>\n<div style=\"background: #fff; border: 1px solid #e2e8f0; border-top: 3px solid #1e3a5f; border-radius: 4px; padding: 16px 18px;\">\n<p style=\"font-size: 10px; font-weight: 800; letter-spacing: 2px; text-transform: uppercase; color: #1e3a5f; margin: 0 0 10px;\">Alega\u00e7\u00f5es de sustentabilidade de embalagens da IBM para marcas coreanas<\/p>\n<p style=\"font-size: 14px; color: #374151; margin: 0; line-height: 1.65;\">As marcas coreanas de cosm\u00e9ticos e bens de consumo de massa (FMCG) comunicam cada vez mais a sustentabilidade das embalagens em seu marketing de produtos (relat\u00f3rios ESG, selo de sustentabilidade Naver Smart Store, certifica\u00e7\u00e3o ambiental INCI para marcas de cosm\u00e9ticos coreanas). A produ\u00e7\u00e3o totalmente el\u00e9trica com a m\u00e1quina IBM ZQ60HE oferece uma comprova\u00e7\u00e3o quantific\u00e1vel de redu\u00e7\u00e3o de energia em compara\u00e7\u00e3o com a produ\u00e7\u00e3o hidr\u00e1ulica com a IBM, que os clientes de marcas coreanas podem usar na comunica\u00e7\u00e3o sobre sustentabilidade de seus produtos: as embalagens IBM produzidas na m\u00e1quina totalmente el\u00e9trica ZQ60HE consomem aproximadamente 30% a menos de energia de fabrica\u00e7\u00e3o por embalagem do que embalagens equivalentes produzidas em m\u00e1quinas hidr\u00e1ulicas IBM \u2014 uma comprova\u00e7\u00e3o verific\u00e1vel de sustentabilidade do processo de produ\u00e7\u00e3o, apoiada pelos dados de medi\u00e7\u00e3o de energia da Korea Ever-Power comparando a ZQ60HE com a ZQ60 hidr\u00e1ulica. A Korea Ever-Power fornece aos clientes de marcas coreanas o certificado de energia de produ\u00e7\u00e3o da ZQ60HE (consumo de energia por 1.000 embalagens produzidas) para fins de relat\u00f3rios ESG e comprova\u00e7\u00e3o da alega\u00e7\u00e3o ambiental do produto, de acordo com as diretrizes de marketing verde da Comiss\u00e3o Coreana de Com\u00e9rcio Justo.<\/p>\n<\/div>\n<\/div>\n<figure style=\"margin: 0 0 0;\"><img decoding=\"async\" style=\"width: 100%; height: auto; border-radius: 3px; display: block; border: 1px solid #cbd5e0;\" title=\"IBM Total System Energy Auxiliary Equipment Korea Ever-Power ZQ Series\" src=\"https:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/07\/IBM-AUXILIARY-EQUIPMENT.webp\" alt=\"Korea Ever-Power IBM production system energy consumption auxiliary equipment chiller dryer conveyor total system kWh analysis hydraulic vs all-electric ZQ60HE comparison\" \/><figcaption style=\"font-size: 12px; color: #64748b; margin-top: 8px; padding-left: 10px; border-left: 2px solid #d97706;\">Os componentes de energia do sistema de produ\u00e7\u00e3o IBM da Korea Ever-Power \u2014 o pacote de equipamentos auxiliares (resfriador, secador, transportador) adiciona de 5 a 12 kWh\/h \u00e0 energia operacional da m\u00e1quina IBM, resultando em um consumo total de energia do sistema ZQ60HE de aproximadamente 18 a 25 kWh\/h (m\u00e1quina: 12 a 15 kWh + auxiliares: 6 a 10 kWh) versus um sistema hidr\u00e1ulico ZQ60 de aproximadamente 26 a 34 kWh\/h (m\u00e1quina: 18 a 22 kWh + auxiliares: 8 a 12 kWh). Os dados de energia total do sistema da Korea Ever-Power est\u00e3o dispon\u00edveis para clientes coreanos no planejamento de custos de eletricidade e fornecimento de energia para suas f\u00e1bricas, j\u00e1 na fase de encomenda das m\u00e1quinas ZQ.<\/figcaption><\/figure>\n<\/section>\n<section style=\"margin: 64px 0 0;\">\n<div style=\"display: flex; align-items: stretch; gap: 0; margin-bottom: 24px;\">\n<div style=\"width: 4px; background: linear-gradient(180deg,#d97706,#f59e0b); border-radius: 2px; flex-shrink: 0;\"><\/div>\n<div style=\"padding: 10px 16px; background: #0f1e35; border-left: none; flex: 1;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 3px;\">PERGUNTAS FREQUENTES SOBRE ENGENHARIA<\/p>\n<h2 id=\"faq\" style=\"font-size: clamp(17px,2.4vw,22px); font-weight: 800; color: #fff; margin: 0; line-height: 1.2;\">Consumo de energia da IBM \u2014 Quest\u00f5es de engenharia<\/h2>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; gap: 2px;\">\n<div style=\"border: 1px solid #e2e8f0; border-radius: 4px 4px 0 0; overflow: hidden; margin-bottom: 2px;\">\n<div style=\"background: #1e3a5f; padding: 13px 18px; display: flex; align-items: center; gap: 10px;\">\n<p><span style=\"background: #d97706; color: #fff; font-size: 10px; font-weight: 800; padding: 2px 8px; border-radius: 2px; flex-shrink: 0;\">Q01<\/span><\/p>\n<p style=\"font-size: 14px; font-weight: bold; color: #fff; margin: 0; line-height: 1.3;\">A economia de energia da ZQ60HE \u00e9 proporcional \u00e0 velocidade de produ\u00e7\u00e3o? Se a ZQ60HE produz 251 TP3T a mais de cont\u00eaineres por hora, o consumo de energia por cont\u00eainer \u00e9 realmente o mesmo que o da ZQ60 hidr\u00e1ulica?<\/p>\n<\/div>\n<div style=\"padding: 18px 20px; background: #fff;\">\n<p style=\"font-size: 15px; color: #374151; margin: 0; line-height: 1.75;\">A economia de energia e o c\u00e1lculo do consumo energ\u00e9tico por cont\u00eainer exigem uma contabiliza\u00e7\u00e3o cuidadosa tanto do consumo quanto da produ\u00e7\u00e3o de energia simultaneamente. A ZQ60HE produz aproximadamente 20 a 251 TP3T a mais de cont\u00eaineres por hora do que a ZQ60 hidr\u00e1ulica em formato equivalente (ciclo seco de 2,5 s da ZQ60HE versus ciclo seco de 4,0 s da ZQ60, o que se traduz em uma taxa de ciclo de produ\u00e7\u00e3o aproximadamente 201 TP3T maior em um ciclo total equivalente com limita\u00e7\u00e3o de resfriamento). O consumo de energia por hora da ZQ60HE \u00e9 aproximadamente 30 a 351 TP3T menor do que o da ZQ60 hidr\u00e1ulica. O efeito combinado no consumo energ\u00e9tico por cont\u00eainer: energia da ZQ60HE por cont\u00eainer = 12-15 kWh\/h \u00f7 (cont\u00eaineres ZQ60HE\/hora) versus ZQ60 hidr\u00e1ulica = 18-22 kWh\/h \u00f7 (cont\u00eaineres ZQ60\/hora). Com 10 cavidades, 100 ml de PP IBM: a ZQ60HE com ciclo seco de 2,5 s (ciclo total estimado de 5,5 s com resfriamento) produz aproximadamente 6.545 recipientes\/hora a 12 kWh\/h = 1,83 Wh\/recipiente. A ZQ60 hidr\u00e1ulica com ciclo seco de 4,0 s (ciclo total estimado de 7,0 s) produz aproximadamente 5.142 recipientes\/hora a 20 kWh\/h = 3,89 Wh\/recipiente. Compara\u00e7\u00e3o de energia por recipiente: ZQ60HE a 1,83 Wh\/recipiente versus ZQ60 hidr\u00e1ulica a 3,89 Wh\/recipiente \u2014 a ZQ60HE utiliza aproximadamente 53% a menos de energia por recipiente IBM produzido, combinando a redu\u00e7\u00e3o do consumo de energia e o aumento da taxa de produ\u00e7\u00e3o. Essa vantagem energ\u00e9tica por cont\u00eainer \u00e9 maior do que a porcentagem de economia de energia por hora, porque a ZQ60HE produz mais cont\u00eaineres por kWh do que a ZQ60 hidr\u00e1ulica, tornando a ZQ60HE a escolha claramente superior tanto em custo absoluto de energia por hora quanto em intensidade energ\u00e9tica por cont\u00eainer produzido.<\/p>\n<\/div>\n<\/div>\n<div style=\"border: 1px solid #e2e8f0; overflow: hidden; margin-bottom: 2px;\">\n<div style=\"background: #1e3a5f; padding: 13px 18px; display: flex; align-items: center; gap: 10px;\">\n<p><span style=\"background: #d97706; color: #fff; font-size: 10px; font-weight: 800; padding: 2px 8px; border-radius: 2px; flex-shrink: 0;\">Q 02<\/span><\/p>\n<p style=\"font-size: 14px; font-weight: bold; color: #fff; margin: 0; line-height: 1.3;\">Qual \u00e9 o perfil de demanda de energia do ZQ60HE para o planejamento da infraestrutura el\u00e9trica de f\u00e1bricas na Coreia?<\/p>\n<\/div>\n<div style=\"padding: 18px 20px; background: #fff;\">\n<p style=\"font-size: 15px; color: #374151; margin: 0; line-height: 1.75;\">O perfil de demanda de energia do ZQ60HE para o planejamento da infraestrutura el\u00e9trica de f\u00e1bricas coreanas difere do ZQ60 hidr\u00e1ulico em um aspecto crucial: o ZQ60HE gera picos de demanda de energia de curta dura\u00e7\u00e3o (pico de 35-45 kW durante a fase de inje\u00e7\u00e3o de 0,8 s) em intervalos de aproximadamente 4-5 segundos (um pico por ciclo IBM), enquanto o ZQ60 hidr\u00e1ulico apresenta uma demanda cont\u00ednua relativamente constante de 18-22 kW. A infraestrutura el\u00e9trica de f\u00e1bricas coreanas (capacidade do transformador, classifica\u00e7\u00e3o do painel de distribui\u00e7\u00e3o e dimensionamento dos cabos de alimenta\u00e7\u00e3o) deve acomodar a demanda de pico do ZQ60HE, e n\u00e3o a demanda m\u00e9dia, para um projeto el\u00e9trico adequado. A Korea Ever-Power recomenda as seguintes especifica\u00e7\u00f5es de infraestrutura el\u00e9trica para o ZQ60HE no planejamento de f\u00e1bricas coreanas: alimenta\u00e7\u00e3o de energia de entrada: transformador trif\u00e1sico com capacidade m\u00ednima de 45 kVA para o circuito da m\u00e1quina ZQ60HE (disjuntor de 45 kVA \u00f7 (380 V \u00d7 \u221a3) = 68 A, fornecendo capacidade para demanda de pico de 35-45 kW com margem adequada). Note que a demanda m\u00e9dia do ZQ60HE, de 12 a 15 kWh\/h, \u00e9 de aproximadamente 12 a 15 kVA \u2014 significativamente menor que a capacidade do transformador de 45 kVA necess\u00e1ria para a demanda de pico. Corre\u00e7\u00e3o do fator de pot\u00eancia na Coreia: os servoacionamentos ZQ60HE geram pot\u00eancia reativa (fator de pot\u00eancia de aproximadamente 0,8 a 0,88 sem corre\u00e7\u00e3o) \u2014 a tarifa comercial e industrial da Korea Electric Power Corporation (KEPCO) aplica uma penalidade por fator de pot\u00eancia abaixo de 0,9. A Korea Ever-Power recomenda que os clientes do ZQ60HE instalem um banco de capacitores com corre\u00e7\u00e3o autom\u00e1tica do fator de pot\u00eancia (APFC) (com capacidade de 5 a 10 kVAr para o ZQ60HE) para manter o fator de pot\u00eancia da KEPCO acima de 0,9 e evitar a sobretaxa por fator de pot\u00eancia na conta de luz industrial coreana. A Korea Ever-Power fornece o diagrama unifilar el\u00e9trico do ZQ60HE e recomenda\u00e7\u00f5es de dimensionamento do transformador no momento do pedido da m\u00e1quina ZQ60HE para a engenharia el\u00e9trica da f\u00e1brica do cliente coreano.<\/p>\n<\/div>\n<\/div>\n<div style=\"border: 1px solid #e2e8f0; overflow: hidden; margin-bottom: 2px;\">\n<div style=\"background: #1e3a5f; padding: 13px 18px; display: flex; align-items: center; gap: 10px;\">\n<p><span style=\"background: #d97706; color: #fff; font-size: 10px; font-weight: 800; padding: 2px 8px; border-radius: 2px; flex-shrink: 0;\">Q03<\/span><\/p>\n<p style=\"font-size: 14px; font-weight: bold; color: #fff; margin: 0; line-height: 1.3;\">Como se compara o consumo de energia das m\u00e1quinas da IBM com o consumo de energia da resina polim\u00e9rica ao longo de todo o ciclo de vida do produto?<\/p>\n<\/div>\n<div style=\"padding: 18px 20px; background: #fff;\">\n<p style=\"font-size: 15px; color: #374151; margin: 0; line-height: 1.75;\">Considerando o ciclo de vida total do produto (ACV), o consumo de energia das m\u00e1quinas IBM representa uma parcela relativamente pequena do impacto ambiental total da embalagem, em compara\u00e7\u00e3o com a energia consumida na produ\u00e7\u00e3o da resina polim\u00e9rica. A produ\u00e7\u00e3o de resina PP em um craqueador a vapor padr\u00e3o coreano apresenta um consumo de energia incorporada de aproximadamente 70-80 MJ\/kg, do ber\u00e7o ao port\u00e3o (dados de produ\u00e7\u00e3o de PP do ECOINVENT 3.8). Portanto, uma garrafa de PP IBM de 10 g cont\u00e9m aproximadamente 700-800 kJ (0,19-0,22 kWh) de energia incorporada no pol\u00edmero. O consumo de energia das m\u00e1quinas IBM para produzir a mesma garrafa de PP de 10 g, em uma usina hidr\u00e1ulica ZQ60 com consumo de 20 kWh\/h e produ\u00e7\u00e3o de 9.000 garrafas\/hora, resulta em 2,22 Wh\/garrafa, ou seja, 0,0022 kWh\/garrafa. A energia consumida pelas m\u00e1quinas IBM (0,0022 kWh) corresponde a aproximadamente 1,21 TP3T da energia incorporada no pol\u00edmero (0,19-0,22 kWh) no n\u00edvel da garrafa. Isso significa que a energia de produ\u00e7\u00e3o da resina PP \u00e9 aproximadamente 50 a 100 vezes maior do que a energia de processamento por garrafa da m\u00e1quina IBM. A economia de energia de 531 TP3T por recipiente (conforme Q01 acima) proporcionada pela ZQ60HE reduz a energia de processamento da m\u00e1quina IBM de aproximadamente 0,0039 kWh\/garrafa (ZQ60 hidr\u00e1ulica) para 0,0018 kWh\/garrafa (ZQ60HE) \u2014 economizando 0,0021 kWh por garrafa, ou aproximadamente 11 TP3T da energia incorporada total da garrafa. Marcas coreanas de cosm\u00e9ticos e bens de consumo que buscam reduzir a pegada de carbono total das embalagens de seus produtos devem priorizar a sele\u00e7\u00e3o da resina PP (PP de base biol\u00f3gica da Braskem ou PP de biometanol coreano reduzem a energia incorporada do pol\u00edmero em 60 a 701 TP3T) em vez da otimiza\u00e7\u00e3o do consumo de energia da m\u00e1quina IBM, visto que a escolha do pol\u00edmero tem um impacto de 50 a 100 vezes maior na Avalia\u00e7\u00e3o do Ciclo de Vida (ACV) do que o tipo de m\u00e1quina IBM. No entanto, a economia de energia da ZQ60HE continua sendo valiosa para a redu\u00e7\u00e3o dos custos operacionais de eletricidade e para a gera\u00e7\u00e3o de cr\u00e9ditos de carbono no sistema K-ETS coreano, considerando a economia das tarifas de eletricidade industrial na Coreia.<\/p>\n<\/div>\n<\/div>\n<div style=\"border: 1px solid #e2e8f0; overflow: hidden; margin-bottom: 2px;\">\n<div style=\"background: #1e3a5f; padding: 13px 18px; display: flex; align-items: center; gap: 10px;\">\n<p><span style=\"background: #d97706; color: #fff; font-size: 10px; font-weight: 800; padding: 2px 8px; border-radius: 2px; flex-shrink: 0;\">Q 04<\/span><\/p>\n<p style=\"font-size: 14px; font-weight: bold; color: #fff; margin: 0; line-height: 1.3;\">A vantagem energ\u00e9tica do ZQ60HE se mant\u00e9m em impressoras IBM de grande formato (garrafa de 1 litro em impressoras totalmente el\u00e9tricas de grande formato equivalentes ao ZQ60HE)?<\/p>\n<\/div>\n<div style=\"padding: 18px 20px; background: #fff;\">\n<p style=\"font-size: 15px; color: #374151; margin: 0; line-height: 1.75;\">A oferta atual de m\u00e1quinas IBM totalmente el\u00e9tricas da s\u00e9rie ZQ da Korea Ever-Power limita-se ao modelo ZQ60HE, equivalente \u00e0 faixa de formato hidr\u00e1ulico ZQ60 (IBM de 30 a 500 ml). A Korea Ever-Power n\u00e3o oferece atualmente vers\u00f5es totalmente el\u00e9tricas dos modelos ZQ80, ZQ110 ou ZQ135 \u2014 o segmento de IBM de grande formato (500 ml a 1 L) \u00e9 atendido apenas pelas m\u00e1quinas hidr\u00e1ulicas ZQ80\/ZQ110\/ZQ135. Para clientes coreanos que utilizam IBM de grande formato (500 ml a 1 L) em m\u00e1quinas hidr\u00e1ulicas ZQ80\/ZQ110\/ZQ135, o princ\u00edpio de economia de energia das m\u00e1quinas IBM totalmente el\u00e9tricas aplica-se teoricamente \u2014 uma m\u00e1quina IBM totalmente el\u00e9trica de 500 ml a 1 L proporcionaria uma economia de energia compar\u00e1vel \u00e0 das m\u00e1quinas hidr\u00e1ulicas de grande formato (30-351 TP3T). No entanto, os sistemas de acionamento totalmente el\u00e9tricos com a for\u00e7a de aperto de 800 a 1.350 kN necess\u00e1ria para os modelos ZQ80 a ZQ135 s\u00e3o tecnicamente mais complexos (servomotores maiores e atuadores de fuso de esferas para aplica\u00e7\u00f5es de alta for\u00e7a) e comercialmente menos dispon\u00edveis no mercado asi\u00e1tico de m\u00e1quinas IBM. A Korea Ever-Power est\u00e1 monitorando o desenvolvimento global de m\u00e1quinas IBM totalmente el\u00e9tricas em grande escala e anunciar\u00e1 a expans\u00e3o da s\u00e9rie ZQ para sistemas totalmente el\u00e9tricos caso a tecnologia com desempenho equivalente ao dos modelos ZQ80 a ZQ135 e custo de capital competitivo esteja dispon\u00edvel comercialmente. A recomenda\u00e7\u00e3o atual da Korea Ever-Power para clientes de m\u00e1quinas IBM de grande formato preocupados com o custo de energia \u00e9 a seguinte: o sistema hidr\u00e1ulico ZQ80\/ZQ110\/ZQ135 com op\u00e7\u00e3o de bomba de deslocamento vari\u00e1vel (dispon\u00edvel nos modelos ZQ110 e ZQ135) reduz o consumo de energia da bomba hidr\u00e1ulica em 15 a 201 TPM em compara\u00e7\u00e3o com a configura\u00e7\u00e3o padr\u00e3o de bomba de deslocamento fixo, diminuindo parcialmente a diferen\u00e7a de energia em rela\u00e7\u00e3o \u00e0s m\u00e1quinas IBM totalmente el\u00e9tricas de grande formato.<\/p>\n<\/div>\n<\/div>\n<div style=\"border: 1px solid #e2e8f0; overflow: hidden; margin-bottom: 2px;\">\n<div style=\"background: #1e3a5f; padding: 13px 18px; display: flex; align-items: center; gap: 10px;\">\n<p><span style=\"background: #d97706; color: #fff; font-size: 10px; font-weight: 800; padding: 2px 8px; border-radius: 2px; flex-shrink: 0;\">Q05<\/span><\/p>\n<p style=\"font-size: 14px; font-weight: bold; color: #fff; margin: 0; line-height: 1.3;\">Que equipamento de medi\u00e7\u00e3o a Korea Ever-Power recomenda para medir o consumo de energia do gerador ZQ60HE nas instala\u00e7\u00f5es do cliente coreano?<\/p>\n<\/div>\n<div style=\"padding: 18px 20px; background: #fff;\">\n<p style=\"font-size: 15px; color: #374151; margin: 0; line-height: 1.75;\">A Korea Ever-Power recomenda tr\u00eas op\u00e7\u00f5es de medi\u00e7\u00e3o de energia para clientes coreanos da IBM que desejam verificar de forma independente o consumo de energia hidr\u00e1ulica do ZQ60HE em compara\u00e7\u00e3o com o ZQ60 em suas instala\u00e7\u00f5es de produ\u00e7\u00e3o na Coreia. Medidor de energia de circuito dedicado (recomendado): instale um medidor de energia classe 0,5 (medidor de kWh com sa\u00edda de pulso, em conformidade com a norma IEC 62053-22) no circuito de alimenta\u00e7\u00e3o dedicado do ZQ60HE no quadro de distribui\u00e7\u00e3o da f\u00e1brica coreana \u2014 fornece o consumo de kWh por hora, por turno e por lote de produ\u00e7\u00e3o para registro de energia de lotes GMP coreanos e monitoramento do fator de pot\u00eancia da KEPCO. A Korea Ever-Power recomenda o medidor de energia Carlo Gavazzi EM24 ou equivalente, com certifica\u00e7\u00e3o coreana e classifica\u00e7\u00e3o energ\u00e9tica, para monitoramento de energia do ZQ60HE em instala\u00e7\u00f5es GMP farmac\u00eauticas ou cosm\u00e9ticas coreanas. Monitoramento de energia integrado \u00e0 IHM (recurso padr\u00e3o do ZQ60HE): A IHM do ZQ60HE inclui um visor integrado para monitoramento de energia do servoacionamento, exibindo a demanda instant\u00e2nea de energia (kW) e o consumo cumulativo de energia (kWh) a partir da medi\u00e7\u00e3o de energia do inversor do servoacionamento \u2014 precis\u00e3o de aproximadamente \u00b15% no ponto de opera\u00e7\u00e3o de produ\u00e7\u00e3o do ZQ60HE. Os clientes coreanos podem ler os dados de energia do servoacionamento do ZQ60HE diretamente na IHM para relat\u00f3rios de energia de fim de turno e rastreamento de energia em lotes de produ\u00e7\u00e3o da IBM, sem a necessidade de equipamentos de medi\u00e7\u00e3o externos. Medidor inteligente KEPCO AMI: Os clientes industriais de energia el\u00e9trica coreanos conectados ao sistema de Infraestrutura Avan\u00e7ada de Medi\u00e7\u00e3o (AMI) da KEPCO podem solicitar dados de demanda de energia el\u00e9trica em intervalos de 15 minutos em seu portal online da KEPCO \u2014 fornecendo dados de demanda de energia em n\u00edvel de f\u00e1brica que podem ser correlacionados com os cronogramas de produ\u00e7\u00e3o do ZQ60HE para benchmarking de energia, sem a necessidade de instalar equipamentos de medi\u00e7\u00e3o adicionais no n\u00edvel do circuito da m\u00e1quina IBM. Todos os tr\u00eas m\u00e9todos de medi\u00e7\u00e3o fornecem precis\u00e3o suficiente no consumo de energia para a an\u00e1lise de ROI do investimento em m\u00e1quinas IBM na Coreia, comparando o ZQ60HE totalmente el\u00e9trico com o ZQ60 hidr\u00e1ulico nas condi\u00e7\u00f5es de produ\u00e7\u00e3o dos clientes coreanos.<\/p>\n<\/div>\n<\/div>\n<div style=\"border: 1px solid #e2e8f0; border-radius: 0 0 4px 4px; overflow: hidden; margin-bottom: 64px;\">\n<div style=\"background: #1e3a5f; padding: 13px 18px; display: flex; align-items: center; gap: 10px;\">\n<p><span style=\"background: #d97706; color: #fff; font-size: 10px; font-weight: 800; padding: 2px 8px; border-radius: 2px; flex-shrink: 0;\">Q06<\/span><\/p>\n<p style=\"font-size: 14px; font-weight: bold; color: #fff; margin: 0; line-height: 1.3;\">Como a Korea Ever-Power apresenta dados de economia de energia aos clientes coreanos para auxiliar na decis\u00e3o de investimento no modelo ZQ60HE?<\/p>\n<\/div>\n<div style=\"padding: 18px 20px; background: #fff;\">\n<p style=\"font-size: 15px; color: #374151; margin: 0; line-height: 1.75;\">A Korea Ever-Power fornece aos clientes coreanos da IBM um modelo de investimento em economia de energia para o gerador ZQ60HE em formato Microsoft Excel, na fase de cota\u00e7\u00e3o, para auxiliar na tomada de decis\u00e3o de investimento no ZQ60HE. O modelo de energia da Korea Ever-Power para o ZQ60HE considera os seguintes par\u00e2metros: horas de produ\u00e7\u00e3o di\u00e1rias planejadas pelo cliente coreano (8\/12\/16\/24), dias de produ\u00e7\u00e3o planejados por ano (250\/300), formato de produ\u00e7\u00e3o planejado (30 ml\/50 ml\/100 ml\/200 ml\/350 ml PP), tarifa de eletricidade atual ou planejada da KEPCO (tarifa industrial A ou B), pre\u00e7o cotado do ZQ60HE e pre\u00e7o cotado do equivalente hidr\u00e1ulico do ZQ60 (para c\u00e1lculo do pr\u00eamio de custo de capital). Resultados do modelo: economia anual de energia (kWh\/ano), economia anual no custo de energia (KRW\/ano, considerando a tarifa da KEPCO do cliente), per\u00edodo de retorno do investimento (payback) do pr\u00eamio de capital do ZQ60HE apenas com base na economia de energia, VPL (valor presente l\u00edquido) de 10 anos da economia de energia com a taxa de desconto coreana de 5% e redu\u00e7\u00e3o de emiss\u00f5es de CO\u2082 com base no fator de emiss\u00e3o da rede da KEPCO para o relat\u00f3rio ESG coreano. A equipe de vendas coreana da Korea Ever-Power apresenta o modelo de economia de energia do ZQ60HE durante a visita t\u00e9cnica ao cliente coreano como parte do processo padr\u00e3o de cota\u00e7\u00e3o do ZQ60HE, permitindo que os compradores coreanos de m\u00e1quinas IBM fa\u00e7am uma compara\u00e7\u00e3o de investimento informada entre o ZQ60HE totalmente el\u00e9trico e o ZQ60 hidr\u00e1ulico, considerando o custo total de propriedade em 10 anos, em vez de apenas o custo de capital. Entre em contato com a Korea Ever-Power em Ansan-si para receber o modelo de economia de energia do ZQ60HE para as especifica\u00e7\u00f5es do seu programa de produ\u00e7\u00e3o IBM na Coreia.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<div style=\"margin: 0 0 72px; background: #0f1e35; border-radius: 4px; overflow: hidden; position: relative;\">\n<div style=\"height: 4px; background: linear-gradient(90deg,#d97706,#f59e0b,#d97706);\"><\/div>\n<div style=\"position: absolute; right: 0; top: 0; bottom: 0; width: 40%; background: linear-gradient(135deg,transparent 0%,rgba(30,58,95,0.5) 100%); pointer-events: none;\"><\/div>\n<div style=\"position: relative; padding: clamp(32px,5vw,52px) clamp(24px,4vw,48px); text-align: center;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 14px;\">Consulta de energia ZQ60HE \u00b7 Coreia Ever-Power<\/p>\n<h2 style=\"font-size: clamp(18px,3vw,28px); font-weight: 900; color: #fff; margin: 0 0 14px; letter-spacing: -0.5px;\">Est\u00e1 avaliando a economia de energia do ZQ60HE para o seu programa IBM?<\/h2>\n<p style=\"font-size: 15px; color: #94a3b8; max-width: 520px; margin: 0 auto 28px; line-height: 1.65;\">A Korea Ever-Power fornece um modelo de economia de energia comparando o ZQ60HE com o ZQ60 hidr\u00e1ulico, uma an\u00e1lise de custos de 10 anos, um c\u00e1lculo da economia de energia da tarifa da KEPCO e um certificado de redu\u00e7\u00e3o de CO\u2082 para auxiliar na tomada de decis\u00f5es de investimento da IBM na Coreia.<\/p>\n<p><a style=\"display: inline-flex; align-items: center; gap: 8px; background: #d97706; color: #fff; padding: 14px 36px; border-radius: 3px; text-decoration: none; font-weight: 800; font-size: 14px; letter-spacing: 0.5px; text-transform: uppercase;\" href=\"https:\/\/isbm-blow-molding.com\/pt\/contact-us\/\">Solicite uma an\u00e1lise de economia de energia. <span style=\"font-size: 16px;\">\u2192<\/span><\/a><\/p>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\"><em>Editor: Cxm<\/em><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>IBM ENERGY CONSUMPTION \u00b7 HYDRAULIC vs ALL-ELECTRIC \u00b7 KOREA EVER-POWER ZQ SERIES IBM Energy Consumption: Hydraulic vs All-Electric ZQ60HE Comparison Energy cost is the second-largest variable production cost in IBM after polymer resin \u2014 and the energy consumption difference between hydraulic and all-electric IBM machines is significant enough to affect machine investment economics over 10-year [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[24],"tags":[],"class_list":["post-1144","post","type-post","status-publish","format-standard","hentry","category-technical-deep-dive"],"_links":{"self":[{"href":"https:\/\/isbm-blow-molding.com\/pt\/wp-json\/wp\/v2\/posts\/1144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isbm-blow-molding.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isbm-blow-molding.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isbm-blow-molding.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/isbm-blow-molding.com\/pt\/wp-json\/wp\/v2\/comments?post=1144"}],"version-history":[{"count":2,"href":"https:\/\/isbm-blow-molding.com\/pt\/wp-json\/wp\/v2\/posts\/1144\/revisions"}],"predecessor-version":[{"id":1146,"href":"https:\/\/isbm-blow-molding.com\/pt\/wp-json\/wp\/v2\/posts\/1144\/revisions\/1146"}],"wp:attachment":[{"href":"https:\/\/isbm-blow-molding.com\/pt\/wp-json\/wp\/v2\/media?parent=1144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isbm-blow-molding.com\/pt\/wp-json\/wp\/v2\/categories?post=1144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isbm-blow-molding.com\/pt\/wp-json\/wp\/v2\/tags?post=1144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}