{"id":1198,"date":"2026-07-10T07:50:45","date_gmt":"2026-07-10T07:50:45","guid":{"rendered":"https:\/\/isbm-blow-molding.com\/?p=1198"},"modified":"2026-07-10T07:50:45","modified_gmt":"2026-07-10T07:50:45","slug":"all-electric-ibm-machine-guide-zq60he-vs-hydraulic-ibm","status":"publish","type":"post","link":"https:\/\/isbm-blow-molding.com\/fr\/all-electric-ibm-machine-guide-zq60he-vs-hydraulic-ibm\/","title":{"rendered":"Guide des machines IBM enti\u00e8rement \u00e9lectriques\u00a0: ZQ60HE vs IBM hydraulique"},"content":{"rendered":"<div style=\"margin: 0; padding: 0; font-family: 'Helvetica Neue',Helvetica,Arial,sans-serif; color: #1a2332; line-height: 1.78; background: #f0f3f7; overflow-x: hidden;\">\n<header style=\"position: relative; min-height: min(600px,88vh); display: flex; align-items: flex-end; width: 100%; background: #04080c; background-image: linear-gradient(155deg,rgba(4,6,10,0.97) 0%,rgba(6,10,18,0.93) 52%,rgba(10,16,28,0.60) 100%),url('https:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/07\/IBM-PRODUCTION-LINE-COMPONENTS.webp'); background-size: cover; background-position: center 40%;\">\n<div style=\"position: absolute; top: 0; left: 0; right: 0; height: 5px; background: linear-gradient(90deg,#d97706,#f59e0b,#d97706);\"><\/div>\n<div style=\"position: absolute; bottom: -1px; left: 0; right: 0; height: 56px; background: #f0f3f7; clip-path: polygon(0 100%,100% 100%,100% 0);\"><\/div>\n<div style=\"position: relative; z-index: 2; width: 100%; padding: clamp(48px,7vw,96px) clamp(20px,5vw,60px) clamp(52px,6vw,84px); box-sizing: border-box;\">\n<div style=\"display: inline-flex; align-items: center; gap: 8px; margin-bottom: 20px;\">\n<div style=\"width: 28px; height: 3px; background: #d97706;\"><\/div>\n<p><span style=\"font-size: 10px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #f59e0b;\">IBM 100% \u00c9LECTRIQUE \u00b7 ZQ60HE \u00b7 SANS HUILE HYDRAULIQUE \u00b7 COR\u00c9E EVER-POWER<\/span><\/p>\n<div style=\"width: 28px; height: 3px; background: #d97706;\"><\/div>\n<\/div>\n<h1 style=\"font-size: clamp(26px,4.6vw,46px); font-weight: 900; color: #fff; line-height: 1.1; margin: 0 0 20px; letter-spacing: -0.8px; max-width: 720px;\">Guide des machines IBM enti\u00e8rement \u00e9lectriques\u00a0:<br \/>\n<span style=\"color: #f59e0b;\">ZQ60HE<\/span> par rapport \u00e0 IBM hydraulique<\/h1>\n<p style=\"font-size: clamp(14px,1.9vw,17px); color: #94a3b8; line-height: 1.7; margin: 0 0 30px; max-width: 620px;\">La machine de moulage par injection-soufflage enti\u00e8rement \u00e9lectrique Ever-Power EP-ZQ60HE de Cor\u00e9e est une machine \u00e0 grande vitesse. Chaque mouvement est assur\u00e9 par des servomoteurs, sans aucune intervention d'huile hydraulique. La ZQ60HE offre un temps de cycle environ 20% plus rapide qu'une ZQ60 hydraulique \u00e9quivalente, consomme environ 30% d'\u00e9nergie en moins par contenant et \u00e9limine tout risque de contamination par huile hydraulique, un atout majeur pour les environnements de production pharmaceutiques et cosm\u00e9tiques de haute qualit\u00e9. Ce guide pr\u00e9sente l'architecture technique de la ZQ60HE, ses performances sup\u00e9rieures \u00e0 celles des machines hydrauliques et les applications de production o\u00f9 le tout \u00e9lectrique offre le meilleur retour sur investissement.<\/p>\n<div style=\"display: flex; flex-wrap: wrap; gap: 6px;\"><span style=\"background: rgba(217,119,6,0.15); border: 1px solid rgba(217,119,6,0.45); color: #fbbf24; font-size: 11px; font-weight: bold; padding: 4px 12px; border-radius: 2px; letter-spacing: 1px; text-transform: uppercase;\">Huile hydraulique z\u00e9ro<\/span><span style=\"background: rgba(255,255,255,0.06); border: 1px solid rgba(255,255,255,0.15); color: #94a3b8; font-size: 11px; font-weight: bold; padding: 4px 12px; border-radius: 2px; letter-spacing: 1px; text-transform: uppercase;\">Cycle plus rapide 20%<\/span><span style=\"background: rgba(255,255,255,0.06); border: 1px solid rgba(255,255,255,0.15); color: #94a3b8; font-size: 11px; font-weight: bold; padding: 4px 12px; border-radius: 2px; letter-spacing: 1px; text-transform: uppercase;\">30% \u00c9conomie d'\u00e9nergie<\/span><\/div>\n<p style=\"font-size: 11px; color: #475569; margin: 22px 0 0; letter-spacing: 1px;\">COR\u00c9E EVER-POWER \u00b7 ANSAN-SI, GYEONGGI-DO \u00b7 JUILLET 2026<\/p>\n<\/div>\n<\/header>\n<p>&nbsp;<\/p>\n<div style=\"background: #0f1e35; border: 1px solid #1e3a5f; border-left: 4px solid #d97706; border-radius: 4px; padding: 24px 28px; margin: 52px 0 0;\">\n<div style=\"display: flex; align-items: center; gap: 10px; margin-bottom: 18px;\">\n<div style=\"width: 16px; height: 16px; border: 2px solid #d97706; border-radius: 50%; display: flex; align-items: center; justify-content: center; flex-shrink: 0;\">\n<div style=\"width: 6px; height: 6px; background: #d97706; border-radius: 50%;\"><\/div>\n<\/div>\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0;\">DONN\u00c9ES CL\u00c9S DE PERFORMANCE DU ZQ60HE<\/p>\n<\/div>\n<div style=\"display: grid; grid-template-columns: repeat(auto-fit,minmax(min(100%,170px),1fr)); gap: 1px; background: #1e3a5f;\">\n<div style=\"background: #0f1e35; padding: 16px 18px;\">\n<p style=\"font-size: 10px; font-weight: bold; letter-spacing: 2px; text-transform: uppercase; color: #475569; margin: 0 0 6px;\">VITESSE DU CYCLE<\/p>\n<p style=\"font-size: 24px; font-weight: 900; color: #f59e0b; margin: 0 0 4px;\">~20% Plus rapide<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">Le temps de cycle du ZQ60HE est environ 20% plus court que celui du ZQ60 hydraulique pour un m\u00eame format de contenant (8,2 s contre environ 10 s pour une bouteille de 30 ml), permettant une production d'environ 115\u00a0000 bouteilles par 24 heures \u00e0 pleine capacit\u00e9.<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 16px 18px;\">\n<p style=\"font-size: 10px; font-weight: bold; letter-spacing: 2px; text-transform: uppercase; color: #475569; margin: 0 0 6px;\">\u00c9NERGIE<\/p>\n<p style=\"font-size: 24px; font-weight: 900; color: #f59e0b; margin: 0 0 4px;\">~30% Inf\u00e9rieur<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">La servocommande enti\u00e8rement \u00e9lectrique \u00e9limine la consommation d'\u00e9nergie continue de la pompe hydraulique \u2014 environ 12 kWh\/h pour la ZQ60HE contre 18 \u00e0 22 kWh\/h pour la ZQ60 hydraulique pour la production de flacons de 30 ml<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 16px 18px;\">\n<p style=\"font-size: 10px; font-weight: bold; letter-spacing: 2px; text-transform: uppercase; color: #475569; margin: 0 0 6px;\">CONTAMINATION<\/p>\n<p style=\"font-size: 24px; font-weight: 900; color: #f59e0b; margin: 0 0 4px;\">Risque p\u00e9trolier nul<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">Absence d'huile hydraulique au-dessus de la zone du moule\u00a0: risque z\u00e9ro de contamination de la surface int\u00e9rieure du conteneur IBM par l'huile hydraulique. Exig\u00e9 pour la production IBM en milieu propre conforme aux BPF pharmaceutiques.<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 16px 18px;\">\n<p style=\"font-size: 10px; font-weight: bold; letter-spacing: 2px; text-transform: uppercase; color: #475569; margin: 0 0 6px;\">BRUIT<\/p>\n<p style=\"font-size: 24px; font-weight: 900; color: #f59e0b; margin: 0 0 4px;\">Nettement inf\u00e9rieur<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">Le servomoteur enti\u00e8rement \u00e9lectrique \u00e9limine le bruit de la pompe hydraulique \u2014 le niveau sonore de production du ZQ66HE est nettement inf\u00e9rieur \u00e0 celui des pompes hydrauliques IBM, ce qui le rend id\u00e9al pour les salles blanches cor\u00e9ennes et les environnements de production sensibles au bruit.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<nav style=\"margin: 28px 0 0; background: #fff; border: 1px solid #cbd5e0; border-radius: 4px; padding: 22px 26px; position: relative; overflow: hidden;\">\n<div style=\"position: absolute; inset: 0; background-image: linear-gradient(rgba(30,58,95,0.03) 1px,transparent 1px),linear-gradient(90deg,rgba(30,58,95,0.03) 1px,transparent 1px); background-size: 24px 24px; pointer-events: none;\"><\/div>\n<div style=\"position: relative;\">\n<div style=\"display: flex; align-items: center; gap: 8px; margin-bottom: 14px;\">\n<div style=\"width: 3px; height: 14px; background: #d97706; border-radius: 2px;\"><\/div>\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 2.5px; text-transform: uppercase; color: #1e3a5f; margin: 0;\">INDEX DES DOCUMENTS<\/p>\n<\/div>\n<div style=\"display: grid; grid-template-columns: repeat(auto-fit,minmax(min(100%,270px),1fr)); gap: 2px 24px;\"><a style=\"color: #1e3a5f; text-decoration: none; font-size: 13.5px; padding: 4px 0; display: flex; align-items: baseline; border-bottom: 1px solid #f1f5f9;\" href=\"#s1\"><span style=\"color: #d97706; font-size: 10px; font-weight: 800; margin-right: 8px; flex-shrink: 0;\">01<\/span>Architecture ZQ60HE\u00a0: Servomoteur enti\u00e8rement \u00e9lectrique IBM<\/a><br \/>\n<a style=\"color: #1e3a5f; text-decoration: none; font-size: 13.5px; padding: 4px 0; display: flex; align-items: baseline; border-bottom: 1px solid #f1f5f9;\" href=\"#s2\"><span style=\"color: #d97706; font-size: 10px; font-weight: 800; margin-right: 8px; flex-shrink: 0;\">02<\/span>Comparaison des performances : ZQ60HE vs ZQ60 hydraulique<\/a><br \/>\n<a style=\"color: #1e3a5f; text-decoration: none; font-size: 13.5px; padding: 4px 0; display: flex; align-items: baseline; border-bottom: 1px solid #f1f5f9;\" href=\"#s3\"><span style=\"color: #d97706; font-size: 10px; font-weight: 800; margin-right: 8px; flex-shrink: 0;\">03<\/span>IBM Industrie Pharmaceutique\u00a0: Avantage des salles blanches enti\u00e8rement \u00e9lectriques<\/a><br \/>\n<a style=\"color: #1e3a5f; text-decoration: none; font-size: 13.5px; padding: 4px 0; display: flex; align-items: baseline; border-bottom: 1px solid #f1f5f9;\" href=\"#s4\"><span style=\"color: #d97706; font-size: 10px; font-weight: 800; margin-right: 8px; flex-shrink: 0;\">04<\/span>\u00c9conomies \u00e9nerg\u00e9tiques : Co\u00fbt total de possession du ZQ60HE<\/a><br \/>\n<a style=\"color: #1e3a5f; text-decoration: none; font-size: 13.5px; padding: 4px 0; display: flex; align-items: baseline; border-bottom: 1px solid #f1f5f9;\" href=\"#s5\"><span style=\"color: #d97706; font-size: 10px; font-weight: 800; margin-right: 8px; flex-shrink: 0;\">05<\/span>Sp\u00e9cifications techniques du ZQ60HE<\/a><br \/>\n<a style=\"color: #1e3a5f; text-decoration: none; font-size: 13.5px; padding: 4px 0; display: flex; align-items: baseline; border-bottom: 1px solid #f1f5f9;\" href=\"#s6\"><span style=\"color: #d97706; font-size: 10px; font-weight: 800; margin-right: 8px; flex-shrink: 0;\">06<\/span>Quand choisir le ZQ60HE plut\u00f4t que le ZQ60 hydraulique ?<\/a><br \/>\n<a style=\"color: #1e3a5f; text-decoration: none; font-size: 13.5px; padding: 4px 0; display: flex; align-items: baseline;\" href=\"#faq\"><span style=\"color: #d97706; font-size: 10px; font-weight: 800; margin-right: 8px; flex-shrink: 0;\">FAQ<\/span>Questions d'ing\u00e9nierie IBM tout \u00e9lectrique<\/a><\/div>\n<\/div>\n<\/nav>\n<div style=\"padding: 0px 2%;\">\n<section id=\"s1\" style=\"margin: 64px 0 0;\">\n<div style=\"display: flex; align-items: stretch; gap: 0; margin-bottom: 22px;\">\n<div style=\"width: 4px; background: linear-gradient(180deg,#d97706,#f59e0b); border-radius: 2px; flex-shrink: 0;\"><\/div>\n<div style=\"padding: 10px 16px; background: #fff; border: 1px solid #e2e8f0; border-left: none; flex: 1;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 3px;\">SECTION 01<\/p>\n<h2 style=\"font-size: clamp(17px,2.4vw,22px); font-weight: 800; color: #0f1e35; margin: 0; line-height: 1.2;\">Architecture ZQ60HE\u00a0: Servomoteur enti\u00e8rement \u00e9lectrique IBM<\/h2>\n<\/div>\n<\/div>\n<p style=\"font-size: 16px; margin-bottom: 20px;\">La machine EP-ZQ60HE d'Ever-Power (Cor\u00e9e) remplace tous les actionneurs hydrauliques de la machine IBM ZQ60 standard par des servomoteurs d\u00e9di\u00e9s\u00a0: entra\u00eenement de l'unit\u00e9 d'injection, entra\u00eenement de fermeture, entra\u00eenement de la table rotative, entra\u00eenement du chariot, entra\u00eenement de l'\u00e9jecteur et servomoteur rotatif sont tous des axes servo \u00e9lectriques contr\u00f4l\u00e9s ind\u00e9pendamment. Il en r\u00e9sulte une machine sans syst\u00e8me d'huile hydraulique, sans pompe hydraulique et sans fluide hydraulique au-dessus de la zone du moule. Ce passage d'une architecture hydraulique \u00e0 une architecture enti\u00e8rement \u00e9lectrique modifie fondamentalement le profil de consommation \u00e9nerg\u00e9tique, la vitesse de rotation, le niveau sonore et l'ad\u00e9quation de la machine IBM \u00e0 la production en salle blanche pharmaceutique. Ever-Power (Cor\u00e9e) propose la ZQ60HE comme alternative \u00e0 la machine standard. <a style=\"color: #1e3a5f; font-weight: 600; text-decoration: none;\" href=\"https:\/\/isbm-blow-molding.com\/fr\/product-category\/3-station-isbm-machine\/\">Machine IBM \u00e0 3 postes<\/a> gamme destin\u00e9e aux clients pour lesquels les avantages sp\u00e9cifiques du ZQ60HE justifient un investissement plus important dans la machine par rapport aux \u00e9quivalents hydrauliques.<\/p>\n<figure style=\"margin: 0 0 24px;\"><img decoding=\"async\" style=\"width: 100%; height: auto; border-radius: 3px; display: block; border: 1px solid #cbd5e0;\" title=\"EP-ZQ60HE All-Electric IBM Machine Korea Ever-Power\" src=\"https:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/07\/IBM-PRODUCTION-LINE-COMPONENTS.webp\" alt=\"Korea Ever-Power EP-ZQ60HE all-electric fully electric injection blow molding machine servo motor drive production line for pharmaceutical cosmetic container production\" \/><figcaption style=\"font-size: 12px; color: #64748b; margin-top: 8px; padding-left: 10px; border-left: 2px solid #d97706;\">La machine IBM enti\u00e8rement \u00e9lectrique Ever-Power EP-ZQ60HE de Korea est en production \u2014 le syst\u00e8me de servomoteurs de la ZQ60HE remplace le groupe hydraulique, le moteur de la pompe hydraulique, les v\u00e9rins hydrauliques et les distributeurs de la ZQ60 standard. Ce syst\u00e8me d'entra\u00eenement servo permet une r\u00e9ponse plus rapide de la machine (acc\u00e9l\u00e9ration du servomoteur par rapport au temps de r\u00e9ponse du distributeur hydraulique), un contr\u00f4le de position plus pr\u00e9cis (retour d'information de l'encodeur du servomoteur par rapport au capteur de position hydraulique) et une consommation d'\u00e9nergie \u00e0 la demande (le servomoteur ne consomme de l'\u00e9nergie que pendant le mouvement, contrairement \u00e0 la pompe hydraulique qui fonctionne en continu).<\/figcaption><\/figure>\n<div style=\"background: #0f1e35; border-radius: 4px; overflow: hidden; margin: 0 0 22px; border-top: 3px solid #d97706;\">\n<div style=\"padding: 14px 20px; border-bottom: 1px solid #1e3a5f;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0;\">IMPOSEMENT DU SERVOMOTEUR ZQ60HE \u2014 ARCHITECTURE DE L'AXE DE LA MACHINE<\/p>\n<\/div>\n<div style=\"display: grid; grid-template-columns: repeat(auto-fit,minmax(min(100%,200px),1fr)); gap: 1px; background: #1e3a5f;\">\n<div style=\"background: #0f1e35; padding: 12px 14px;\">\n<p style=\"font-size: 10px; color: #f59e0b; font-weight: bold; margin: 0 0 5px; letter-spacing: 1px; text-transform: uppercase;\">servomoteur d'injection<\/p>\n<p style=\"font-size: 13px; color: #e2e8f0; margin: 0; line-height: 1.6;\">Un servomoteur de 22 kW assure la rotation de la vis d'injection et le mouvement d'injection. Le contr\u00f4le pr\u00e9cis de la vitesse d'injection et du profil de pression via le couple du servomoteur permet une variation de poids d'injection inf\u00e9rieure \u00e0 1% dans les cavit\u00e9s ZQ60HE.<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 12px 14px;\">\n<p style=\"font-size: 10px; color: #f59e0b; font-weight: bold; margin: 0 0 5px; letter-spacing: 1px; text-transform: uppercase;\">Servomoteur de serrage<\/p>\n<p style=\"font-size: 13px; color: #e2e8f0; margin: 0; line-height: 1.6;\">Le serrage des moules d'injection et de soufflage est assur\u00e9 par deux servomoteurs de 15 kW chacun. Le serrage \u00e9lectrique permet une ouverture\/fermeture du moule plus rapide (20-30%) que le serrage hydraulique, principal atout du ZQ60HE par rapport au ZQ60 hydraulique en termes de temps de cycle.<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 12px 14px;\">\n<p style=\"font-size: 10px; color: #f59e0b; font-weight: bold; margin: 0 0 5px; letter-spacing: 1px; text-transform: uppercase;\">servomoteur rotatif<\/p>\n<p style=\"font-size: 13px; color: #e2e8f0; margin: 0; line-height: 1.6;\">Un servomoteur de 2,9 kW actionne la table rotative \u00e0 3 stations. Un codeur absolu de haute pr\u00e9cision garantit un positionnement pr\u00e9cis et r\u00e9p\u00e9table des stations \u00e0 \u00b10,02 mm pr\u00e8s, un point crucial pour l'alignement des barres de noyau \u00e0 chaque changement de station lors de la production \u00e0 cadence \u00e9lev\u00e9e de la ZQ60HE.<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 12px 14px;\">\n<p style=\"font-size: 10px; color: #f59e0b; font-weight: bold; margin: 0 0 5px; letter-spacing: 1px; text-transform: uppercase;\">servomoteur d'alimentation en mat\u00e9riau<\/p>\n<p style=\"font-size: 13px; color: #e2e8f0; margin: 0; line-height: 1.6;\">Un servomoteur de 18 kW actionne l'alimentateur automatique de mat\u00e9riau. Le contr\u00f4le volum\u00e9trique du PEHD, du PP, du PEBD et d'autres mat\u00e9riaux IBM dans la tr\u00e9mie du canon assure un d\u00e9bit d'alimentation constant, garantissant ainsi une temp\u00e9rature et un poids d'injection stables dans le canon ZQ60HE.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"s2\" style=\"margin: 56px 0 0;\">\n<div style=\"display: flex; align-items: stretch; gap: 0; margin-bottom: 22px;\">\n<div style=\"width: 4px; background: linear-gradient(180deg,#d97706,#f59e0b); border-radius: 2px; flex-shrink: 0;\"><\/div>\n<div style=\"padding: 10px 16px; background: #fff; border: 1px solid #e2e8f0; border-left: none; flex: 1;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 3px;\">SECTION 02<\/p>\n<h2 style=\"font-size: clamp(17px,2.4vw,22px); font-weight: 800; color: #0f1e35; margin: 0; line-height: 1.2;\">Comparaison des performances : ZQ60HE vs ZQ60 hydraulique<\/h2>\n<\/div>\n<\/div>\n<figure style=\"margin: 0 0 22px;\"><img decoding=\"async\" style=\"width: 100%; height: auto; border-radius: 3px; display: block; border: 1px solid #cbd5e0;\" title=\"ZQ60HE vs Hydraulic ZQ60 IBM Performance Korea Ever-Power\" src=\"https:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/07\/IBM-mold-3.webp\" alt=\"IBM mould tooling on Korea Ever-Power ZQ60HE all-electric machine showing core rod and cavity precision positioning enabled by servo encoder ZQ60HE vs hydraulic ZQ60 performance comparison\" \/><figcaption style=\"font-size: 12px; color: #64748b; margin-top: 8px; padding-left: 10px; border-left: 2px solid #d97706;\">La pr\u00e9cision de l'outillage de moulage IBM sur la ZQ60HE \u2013 le retour d'information de position par servocodeur (\u00b10,02 mm) compar\u00e9 \u00e0 un capteur de position hydraulique (\u00b10,05-0,10 mm) \u2013 am\u00e9liore directement la pr\u00e9cision de fermeture du moule et la r\u00e9p\u00e9tabilit\u00e9 du positionnement des noyaux. \u00c0 chaque cycle de production, la ZQ60HE positionne le moule d'injection, le moule de soufflage et la station de d\u00e9moulage avec une pr\u00e9cision servo-command\u00e9e qu'un actionneur hydraulique ne peut \u00e9galer \u00e0 vitesse \u00e9quivalente.<\/figcaption><\/figure>\n<div style=\"overflow-x: auto; margin: 0 0 22px;\">\n<table style=\"width: 100%; border-collapse: collapse; font-size: 13px; min-width: 500px;\">\n<thead>\n<tr style=\"background: #0f1e35;\">\n<th style=\"color: #f59e0b; padding: 10px 12px; text-align: left; font-weight: bold; border-right: 1px solid #1e3a5f;\">CRIT\u00c8RE<\/th>\n<th style=\"color: #f59e0b; padding: 10px 10px; text-align: center; font-weight: bold; border-right: 1px solid #1e3a5f;\">ZQ60HE (Tout \u00e9lectrique)<\/th>\n<th style=\"color: #94a3b8; padding: 10px 10px; text-align: center; font-weight: bold;\">ZQ60 (Hydraulique)<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr style=\"background: #fff;\">\n<td style=\"padding: 9px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">Dur\u00e9e du cycle (30 ml)<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center; font-weight: bold; color: #d97706;\">~8,2 s (~20% plus rapide)<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; color: #94a3b8;\">~10,0 s<\/td>\n<\/tr>\n<tr style=\"background: #f8fafc;\">\n<td style=\"padding: 9px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">D\u00e9bit maximal sur 24 heures (30 ml)<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center; font-weight: bold; color: #d97706;\">Environ 105 000 \u00e0 115 000 bouteilles<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; color: #94a3b8;\">Environ 86 000 \u00e0 90 000 bouteilles<\/td>\n<\/tr>\n<tr style=\"background: #fff;\">\n<td style=\"padding: 9px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">Consommation d'\u00e9nergie (30 ml)<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center; font-weight: bold; color: #d97706;\">~12 kWh\/h (~30% inf\u00e9rieur)<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; color: #94a3b8;\">~18-22 kWh\/h<\/td>\n<\/tr>\n<tr style=\"background: #f8fafc;\">\n<td style=\"padding: 9px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">huile hydraulique<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center; font-weight: bold; color: #059669;\">Aucun (syst\u00e8me sans huile)<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; color: #94a3b8;\">~80-120 L d'huile hydraulique<\/td>\n<\/tr>\n<tr style=\"background: #fff;\">\n<td style=\"padding: 9px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">niveau sonore<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center; font-weight: bold; color: #d97706;\">Nettement inf\u00e9rieur<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; color: #94a3b8;\">Plus haut (pompe hydraulique)<\/td>\n<\/tr>\n<tr style=\"background: #f8fafc;\">\n<td style=\"padding: 9px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">r\u00e9p\u00e9tabilit\u00e9 de la position<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center; font-weight: bold; color: #d97706;\">\u00b10,02 mm (encodeur servo)<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; color: #94a3b8;\">\u00b10,05-0,10 mm (capteur hydraulique)<\/td>\n<\/tr>\n<tr style=\"background: #fff;\">\n<td style=\"padding: 9px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">salle blanche pharmaceutique<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; text-align: center; font-weight: bold; color: #059669;\">Convient (risque z\u00e9ro li\u00e9 au p\u00e9trole)<\/td>\n<td style=\"padding: 9px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; color: #dc2626;\">Risque (huile au-dessus de moisissures)<\/td>\n<\/tr>\n<tr style=\"background: #f8fafc;\">\n<td style=\"padding: 9px 12px; border-right: 1px solid #e2e8f0; font-weight: 600;\">Investissement en machines<\/td>\n<td style=\"padding: 9px 10px; border-right: 1px solid #e2e8f0; text-align: center; font-weight: bold; color: #d97706;\">Syst\u00e8me servo sup\u00e9rieur<\/td>\n<td style=\"padding: 9px 10px; text-align: center; color: #094a3b8;\">Co\u00fbt de base inf\u00e9rieur<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/section>\n<section id=\"s3\" style=\"margin: 56px 0 0;\">\n<div style=\"display: flex; align-items: stretch; gap: 0; margin-bottom: 22px;\">\n<div style=\"width: 4px; background: linear-gradient(180deg,#d97706,#f59e0b); border-radius: 2px; flex-shrink: 0;\"><\/div>\n<div style=\"padding: 10px 16px; background: #fff; border: 1px solid #e2e8f0; border-left: none; flex: 1;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 3px;\">SECTION 03<\/p>\n<h2 style=\"font-size: clamp(17px,2.4vw,22px); font-weight: 800; color: #0f1e35; margin: 0; line-height: 1.2;\">IBM Industrie Pharmaceutique\u00a0: Avantage des salles blanches enti\u00e8rement \u00e9lectriques<\/h2>\n<\/div>\n<\/div>\n<figure style=\"margin: 0 0 24px;\"><img decoding=\"async\" style=\"width: 100%; height: auto; border-radius: 3px; display: block; border: 1px solid #cbd5e0;\" title=\"ZQ60HE Zero Oil Pharmaceutical IBM Clean Room Korea Ever-Power\" src=\"https:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/07\/IBM-Internal-structure.webp\" alt=\"Korea Ever-Power ZQ60HE all-electric IBM machine internal structure showing servo motor drives zero hydraulic oil above mould area for pharmaceutical clean room GMP injection blow molding production\" \/><figcaption style=\"font-size: 12px; color: #64748b; margin-top: 8px; padding-left: 10px; border-left: 2px solid #d97706;\">La structure interne de la machine ZQ60HE, gr\u00e2ce \u00e0 son architecture \u00e0 servocommande, remplace tous les composants hydrauliques situ\u00e9s au-dessus et autour de la zone de moulage. Sur les machines IBM hydrauliques, les v\u00e9rins hydrauliques d'injection et de soufflage sont positionn\u00e9s directement au-dessus de la zone de moulage, cr\u00e9ant ainsi un risque de fuite ou d'\u00e9coulement d'huile hydraulique susceptible de contaminer l'int\u00e9rieur du conteneur IBM pendant la production. La ZQ60HE \u00e9limine totalement ce risque de contamination, ce qui en fait la plateforme IBM de choix pour la production de conteneurs pharmaceutiques BPF en Cor\u00e9e et dans le monde, o\u00f9 la classification ISO des salles blanches exige l'\u00e9limination de tout risque li\u00e9 \u00e0 l'huile hydraulique au-dessus de la zone de production des conteneurs.<\/figcaption><\/figure>\n<div style=\"display: grid; grid-template-columns: repeat(auto-fit,minmax(min(100%,260px),1fr)); gap: 14px; margin: 0 0 22px;\">\n<div style=\"background: #fff; border: 1px solid #e2e8f0; border-top: 3px solid #d97706; border-radius: 4px; padding: 16px 18px;\">\n<p style=\"font-size: 10px; font-weight: 800; letter-spacing: 2px; text-transform: uppercase; color: #d97706; margin: 0 0 10px;\">Salle blanche IBM pharmaceutique MFDS cor\u00e9enne<\/p>\n<p style=\"font-size: 14px; color: #374151; margin: 0; line-height: 1.65;\">Les directives de production BPF (Bonnes Pratiques de Fabrication) de l'organisme cor\u00e9en MFDS (Medicare Pharmaceuticals and Development Services) recommandent un environnement de salle blanche de classe ISO 7 ou 8 pour la production de conteneurs primaires pharmaceutiques par injection de particules (IBM). Les machines IBM hydrauliques introduisent l'huile hydraulique comme source potentielle de contamination lors de la classification des salles blanches\u00a0; m\u00eame une fuite, m\u00eame minime, au niveau des joints d'\u00e9tanch\u00e9it\u00e9 peut compromettre la lib\u00e9ration des lots de conteneurs pharmaceutiques conformes aux normes cor\u00e9ennes MFDS si elle est d\u00e9tect\u00e9e lors des tests de particules. L'architecture sans huile hydraulique du ZQ60HE \u00e9limine totalement ce risque de contamination, simplifiant ainsi la validation des salles blanches ISO pour les clients pharmaceutiques cor\u00e9ens et r\u00e9duisant le p\u00e9rim\u00e8tre des investigations en cas d'audit MFDS.<\/p>\n<\/div>\n<div style=\"background: #fff; border: 1px solid #e2e8f0; border-top: 3px solid #1e3a5f; border-radius: 4px; padding: 16px 18px;\">\n<p style=\"font-size: 10px; font-weight: 800; letter-spacing: 2px; text-transform: uppercase; color: #1e3a5f; margin: 0 0 10px;\">Conception ascendante pour une production hygi\u00e9nique<\/p>\n<p style=\"font-size: 14px; color: #374151; margin: 0; line-height: 1.65;\">Korea Ever-Power con\u00e7oit la ZQ60HE selon un principe de production ascendant\u00a0: tous les points de lubrification sont situ\u00e9s sous la zone de moulage, ce qui emp\u00eache toute fuite ou migration d\u2019huile de lubrification dans la zone de production des contenants IBM situ\u00e9e au-dessus. La zone de moulage de la ZQ60HE est ainsi exempte de tout risque de contamination par l\u2019huile hydraulique et par les lubrifiants, r\u00e9pondant aux exigences d\u2019hygi\u00e8ne pour la production d\u2019emballages pharmaceutiques et de contenants cosm\u00e9tiques IBM de haute qualit\u00e9. Les clients de marques cor\u00e9ennes ne tol\u00e8rent aucun risque de contamination des documents de fourniture. Ce principe de conception est explicitement mentionn\u00e9 dans la documentation de la ZQ60HE comme une caract\u00e9ristique de la machine IBM conforme aux BPF (Bonnes Pratiques de Fabrication).<\/p>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"s4\" style=\"margin: 56px 0 0;\">\n<div style=\"display: flex; align-items: stretch; gap: 0; margin-bottom: 22px;\">\n<div style=\"width: 4px; background: linear-gradient(180deg,#d97706,#f59e0b); border-radius: 2px; flex-shrink: 0;\"><\/div>\n<div style=\"padding: 10px 16px; background: #fff; border: 1px solid #e2e8f0; border-left: none; flex: 1;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 3px;\">SECTION 04<\/p>\n<h2 style=\"font-size: clamp(17px,2.4vw,22px); font-weight: 800; color: #0f1e35; margin: 0; line-height: 1.2;\">\u00c9conomies \u00e9nerg\u00e9tiques : Co\u00fbt total de possession du ZQ60HE<\/h2>\n<\/div>\n<\/div>\n<p style=\"font-size: 16px; margin-bottom: 20px;\">L'investissement initial plus \u00e9lev\u00e9 pour la ZQ60HE par rapport \u00e0 la ZQ60 hydraulique est compens\u00e9 par deux avantages \u00e9conomiques continus\u00a0: les \u00e9conomies d'\u00e9nergie li\u00e9es au syst\u00e8me d'entra\u00eenement servo et l'augmentation de la production annuelle de conteneurs gr\u00e2ce \u00e0 un cycle de production plus court. Le d\u00e9lai d'amortissement d\u00e9pend du tarif de l'\u00e9lectricit\u00e9 en Cor\u00e9e, du volume de production annuel et du format des conteneurs. Toutefois, le mod\u00e8le de retour sur investissement standard de Korea Ever-Power pour la ZQ60HE d\u00e9montre un amortissement en 2 \u00e0 4\u00a0ans pour les programmes IBM des industries pharmaceutiques et cosm\u00e9tiques cor\u00e9ennes \u00e0 haut volume, fonctionnant \u00e0 des cadences de production sup\u00e9rieures \u00e0 16\u00a0heures par jour.<\/p>\n<div style=\"background: #0f1e35; border-radius: 4px; padding: 18px 22px; border-top: 3px solid #d97706; margin: 0 0 22px;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 14px;\">AVANTAGE EN MATI\u00c8RE DE CO\u00dbTS D'EXPLOITATION ANNUELS DU ZQ60HE \u2014 MOD\u00c8LE ILLUSTRATIF (collyre en LDPE de 30 ml, tarif d'\u00e9lectricit\u00e9 cor\u00e9en de 120 KRW\/kWh)<\/p>\n<div style=\"display: grid; grid-template-columns: repeat(auto-fit,minmax(min(100%,220px),1fr)); gap: 1px; background: #1e3a5f;\">\n<div style=\"background: #0f1e35; padding: 12px 14px;\">\n<p style=\"font-size: 10px; color: #f59e0b; font-weight: bold; margin: 0 0 5px; letter-spacing: 1px; text-transform: uppercase;\">\u00c9conomies d'\u00e9nergie (annuelles)<\/p>\n<p style=\"font-size: 18px; font-weight: 900; color: #f59e0b; margin: 0 0 3px;\">~KRW 12-18M<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">\u00c9conomie de 6 \u00e0 10 kWh\/h \u00d7 5\u00a0760 heures de production annuelles (16 h\/jour, 360 jours) \u00d7 120 KRW\/kWh = \u00c9conomies de co\u00fbts \u00e9nerg\u00e9tiques de 4 \u00e0 7 millions de KRW par an par ZQ60HE par rapport \u00e0 la ZQ60 hydraulique<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 12px 14px;\">\n<p style=\"font-size: 10px; color: #f59e0b; font-weight: bold; margin: 0 0 5px; letter-spacing: 1px; text-transform: uppercase;\">Production suppl\u00e9mentaire (annuelle)<\/p>\n<p style=\"font-size: 18px; font-weight: 900; color: #f59e0b; margin: 0 0 3px;\">~+21M conteneurs<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">Cycle plus rapide ~20%\u00a0: 2\u00a0100 contenants suppl\u00e9mentaires\/heure \u00d7 5\u00a0760 heures = environ 12 millions de contenants suppl\u00e9mentaires\/an \u00e0 10 cavit\u00e9s, format 30 ml<\/p>\n<\/div>\n<div style=\"background: #0f1e35; padding: 12px 14px;\">\n<p style=\"font-size: 10px; color: #f59e0b; font-weight: bold; margin: 0 0 5px; letter-spacing: 1px; text-transform: uppercase;\">\u00c9conomies d'entretien<\/p>\n<p style=\"font-size: 14px; font-weight: 900; color: #f59e0b; margin: 0 0 3px;\">Co\u00fbt de l'huile hydraulique nul<\/p>\n<p style=\"font-size: 12px; color: #64748b; margin: 0;\">Pas de vidange d'huile hydraulique (g\u00e9n\u00e9ralement 80 \u00e0 120 litres par vidange, toutes les 2\u00a0000 heures), pas de remplacement de joints hydrauliques, pas de remplacement de filtres hydrauliques\u00a0\u2014 \u00e9liminant ainsi les co\u00fbts d'entretien hydraulique de 3 \u00e0 6 millions de wons par an.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section id=\"s5\" style=\"margin: 56px 0 0;\">\n<div style=\"display: flex; align-items: stretch; gap: 0; margin-bottom: 22px;\">\n<div style=\"width: 4px; background: linear-gradient(180deg,#d97706,#f59e0b); border-radius: 2px; flex-shrink: 0;\"><\/div>\n<div style=\"padding: 10px 16px; background: #fff; border: 1px solid #e2e8f0; border-left: none; flex: 1;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 3px;\">SECTION 05<\/p>\n<h2 style=\"font-size: clamp(17px,2.4vw,22px); font-weight: 800; color: #0f1e35; margin: 0; line-height: 1.2;\">Sp\u00e9cifications techniques du ZQ60HE<\/h2>\n<\/div>\n<\/div>\n<figure style=\"margin: 0 0 24px;\"><img decoding=\"async\" style=\"width: 100%; height: auto; border-radius: 3px; display: block; border: 1px solid #cbd5e0;\" title=\"ZQ60HE Auxiliary Equipment Production Line Korea Ever-Power\" src=\"https:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/07\/IBM-AUXILIARY-EQUIPMENT.webp\" alt=\"Korea Ever-Power ZQ60HE all-electric IBM machine auxiliary equipment visual inspection machine mould temperature controller chiller for pharmaceutical cosmetic production line\" \/><figcaption style=\"font-size: 12px; color: #64748b; margin-top: 8px; padding-left: 10px; border-left: 2px solid #d97706;\">\u00c9quipements auxiliaires de la ligne de production ZQ60HE \u2014 Le convoyeur arri\u00e8re du ZQ60HE peut \u00eatre raccord\u00e9 \u00e0 une machine d'inspection visuelle des flacons pour la d\u00e9tection de particules \u00e9trang\u00e8res (norme pour la production pharmaceutique IBM), ainsi qu'\u00e0 des testeurs d'\u00e9tanch\u00e9it\u00e9 lat\u00e9rale et \u00e0 des \u00e9tiqueteuses pour une int\u00e9gration compl\u00e8te de la ligne de production ZQ60HE automatis\u00e9e. Le service d'int\u00e9gration de lignes de production de Korea Ever-Power con\u00e7oit l'agencement complet de la ligne de production IBM, du ZQ60HE aux \u00e9quipements auxiliaires et jusqu'au conditionnement, pour les clients cor\u00e9ens des secteurs pharmaceutique et cosm\u00e9tique.<\/figcaption><\/figure>\n<div style=\"overflow-x: auto; margin: 0 0 22px;\">\n<table style=\"width: 100%; border-collapse: collapse; font-size: 13px; min-width: 500px;\">\n<thead>\n<tr style=\"background: #0f1e35;\">\n<th style=\"color: #f59e0b; padding: 9px 12px; text-align: left; font-weight: bold; border-right: 1px solid #1e3a5f;\">SYST\u00c8ME<\/th>\n<th style=\"color: #f59e0b; padding: 9px 10px; text-align: left; font-weight: bold; border-right: 1px solid #1e3a5f;\">PARAM\u00c8TRE<\/th>\n<th style=\"color: #e2e8f0; padding: 9px 10px; text-align: center; font-weight: bold;\">Valeur ZQ60HE<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr style=\"background: #fff;\">\n<td style=\"padding: 8px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">Injection<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0;\">Diam\u00e8tre de la vis<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; font-weight: bold;\">45 \/ 50 mm<\/td>\n<\/tr>\n<tr style=\"background: #f8fafc;\">\n<td style=\"padding: 8px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">Injection<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0;\">Poids d'injection<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; font-weight: bold;\">280 \/ 360 g<\/td>\n<\/tr>\n<tr style=\"background: #fff;\">\n<td style=\"padding: 8px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">Injection<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0;\">servomoteur d'injection<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; font-weight: bold;\">22 kW<\/td>\n<\/tr>\n<tr style=\"background: #f8fafc;\">\n<td style=\"padding: 8px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">Serrage<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0;\">Force de serrage par injection<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; font-weight: bold;\">400-800 kN (r\u00e9glable)<\/td>\n<\/tr>\n<tr style=\"background: #fff;\">\n<td style=\"padding: 8px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">Serrage<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0;\">force de serrage par soufflage<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; font-weight: bold;\">200 KN<\/td>\n<\/tr>\n<tr style=\"background: #f8fafc;\">\n<td style=\"padding: 8px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">Serrage<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0;\">servomoteur de serrage<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; font-weight: bold;\">15 kW + 15 kW<\/td>\n<\/tr>\n<tr style=\"background: #fff;\">\n<td style=\"padding: 8px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">Moule<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0;\">Dimensions maximales du plateau (L\u00d7l)<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; font-weight: bold;\">600 \u00d7 420 mm<\/td>\n<\/tr>\n<tr style=\"background: #f8fafc;\">\n<td style=\"padding: 8px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">Performance<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0;\">Cycle de s\u00e9chage<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; font-weight: bold;\">2,5 s<\/td>\n<\/tr>\n<tr style=\"background: #fff;\">\n<td style=\"padding: 8px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">Pouvoir<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0;\">Puissance totale<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; font-weight: bold;\">90 kW<\/td>\n<\/tr>\n<tr style=\"background: #f8fafc;\">\n<td style=\"padding: 8px 12px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0; font-weight: 600;\">Pouvoir<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; border-right: 1px solid #e2e8f0;\">Puissance de fonctionnement (r\u00e9elle)<\/td>\n<td style=\"padding: 8px 10px; border-bottom: 1px solid #e2e8f0; text-align: center; font-weight: bold;\">15-25%<\/td>\n<\/tr>\n<tr style=\"background: #fff;\">\n<td style=\"padding: 8px 12px; border-right: 1px solid #e2e8f0; font-weight: 600;\">Machine<\/td>\n<td style=\"padding: 8px 10px; border-right: 1px solid #e2e8f0;\">Poids net \/ Empreinte au sol<\/td>\n<td style=\"padding: 8px 10px; text-align: center; font-weight: bold;\">6 tonnes \/ 3 \u00d7 1,3 \u00d7 1,7 m<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/section>\n<section id=\"s6\" style=\"margin: 56px 0 0;\">\n<div style=\"display: flex; align-items: stretch; gap: 0; margin-bottom: 22px;\">\n<div style=\"width: 4px; background: linear-gradient(180deg,#d97706,#f59e0b); border-radius: 2px; flex-shrink: 0;\"><\/div>\n<div style=\"padding: 10px 16px; background: #fff; border: 1px solid #e2e8f0; border-left: none; flex: 1;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 3px;\">SECTION 06<\/p>\n<h2 style=\"font-size: clamp(17px,2.4vw,22px); font-weight: 800; color: #0f1e35; margin: 0; line-height: 1.2;\">Quand choisir le ZQ60HE plut\u00f4t que le ZQ60 hydraulique ?<\/h2>\n<\/div>\n<\/div>\n<div style=\"display: grid; grid-template-columns: repeat(auto-fit,minmax(min(100%,270px),1fr)); gap: 14px; margin: 0 0 22px;\">\n<div style=\"background: #fff; border: 1px solid #e2e8f0; border-top: 3px solid #d97706; border-radius: 4px; padding: 16px 18px;\">\n<p style=\"font-size: 10px; font-weight: 800; letter-spacing: 2px; text-transform: uppercase; color: #d97706; margin: 0 0 10px;\">Choisissez le ZQ60HE quand :<\/p>\n<div style=\"display: flex; flex-direction: column; gap: 6px;\">\n<div style=\"background: #f8fafc; border-left: 3px solid #d97706; padding: 8px 12px; border-radius: 0 3px 3px 0;\">\n<p style=\"font-size: 13px; color: #374151; margin: 0;\"><strong style=\"color: #0f1e35;\">salle blanche pharmaceutique conforme aux BPF<\/strong> \u2014 Production cor\u00e9enne de contenants primaires pharmaceutiques MFDS n\u00e9cessitant un environnement de salle blanche ISO o\u00f9 le risque de contamination par l'huile hydraulique est inacceptable dans la documentation de validation.<\/p>\n<\/div>\n<div style=\"background: #f8fafc; border-left: 3px solid #f59e0b; padding: 8px 12px; border-radius: 0 3px 3px 0;\">\n<p style=\"font-size: 13px; color: #374151; margin: 0;\"><strong style=\"color: #0f1e35;\">Production \u00e0 grand volume &gt; 20 millions\/an<\/strong> \u2014 programmes o\u00f9 l'avantage du temps de cycle du 20% g\u00e9n\u00e8re une production annuelle de conteneurs suppl\u00e9mentaire significative qui justifie l'investissement premium du ZQ60HE dans un d\u00e9lai de retour sur investissement de 2 \u00e0 4 ans.<\/p>\n<\/div>\n<div style=\"background: #f8fafc; border-left: 3px solid #1e3a5f; padding: 8px 12px; border-radius: 0 3px 3px 0;\">\n<p style=\"font-size: 13px; color: #374151; margin: 0;\"><strong style=\"color: #0f1e35;\">Environnement \u00e0 co\u00fbt d'\u00e9lectricit\u00e9 \u00e9lev\u00e9 en Cor\u00e9e<\/strong> \u2014 Installations cor\u00e9ennes o\u00f9 le co\u00fbt de l'\u00e9lectricit\u00e9 d\u00e9passe 100 KRW\/kWh, ce qui rend les \u00e9conomies d'\u00e9nergie du 30% significatives dans le calcul de la r\u00e9duction des co\u00fbts d'exploitation annuels.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"background: #fff; border: 1px solid #e2e8f0; border-top: 3px solid #1e3a5f; border-radius: 4px; padding: 16px 18px;\">\n<p style=\"font-size: 10px; font-weight: 800; letter-spacing: 2px; text-transform: uppercase; color: #1e3a5f; margin: 0 0 10px;\">Choisissez le ZQ60 hydraulique quand :<\/p>\n<div style=\"display: flex; flex-direction: column; gap: 6px;\">\n<div style=\"background: #f8fafc; border-left: 3px solid #475569; padding: 8px 12px; border-radius: 0 3px 3px 0;\">\n<p style=\"font-size: 13px; color: #374151; margin: 0;\"><strong style=\"color: #0f1e35;\">Programmes IBM \u00e0 faible volume ou de d\u00e9marrage<\/strong> \u2014 nouvelles lignes de production IBM de 5 \u00e0 15 millions de conteneurs par an o\u00f9 la priorit\u00e9 est donn\u00e9e \u00e0 un investissement initial plus faible dans les machines et o\u00f9 la p\u00e9riode de retour sur investissement pour la prime ZQ60HE s'\u00e9tend sur plus de 5 ans.<\/p>\n<\/div>\n<div style=\"background: #f8fafc; border-left: 3px solid #64748b; padding: 8px 12px; border-radius: 0 3px 3px 0;\">\n<p style=\"font-size: 13px; color: #374151; margin: 0;\"><strong style=\"color: #0f1e35;\">Applications IBM non pharmaceutiques<\/strong> \u2014 Production IBM de produits chimiques m\u00e9nagers, d'emballages alimentaires ou de conteneurs industriels en PEHD o\u00f9 les exigences en mati\u00e8re de salles blanches ne s'appliquent pas et o\u00f9 le risque li\u00e9 \u00e0 l'huile hydraulique est acceptable dans l'environnement de production.<\/p>\n<\/div>\n<div style=\"background: #f8fafc; border-left: 3px solid #94a3b8; padding: 8px 12px; border-radius: 0 3px 3px 0;\">\n<p style=\"font-size: 13px; color: #374151; margin: 0;\"><strong style=\"color: #0f1e35;\">Investissement en machines sous contrainte budg\u00e9taire<\/strong> \u2014 Les clients cor\u00e9ens pour qui le co\u00fbt d'investissement inf\u00e9rieur du ZQ60 hydraulique est le crit\u00e8re d'achat primordial et dont l'\u00e9conomie de production ne soutient pas le retour sur investissement du ZQ60HE dans leur p\u00e9riode de r\u00e9cup\u00e9ration requise.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p style=\"font-size: 15px; color: #374151; line-height: 1.7;\">La gamme compl\u00e8te de machines de moulage par injection-soufflage Korea Ever-Power s\u00e9rie ZQ, comprenant les mod\u00e8les ZQ60HE et hydrauliques ZQ40 \u00e0 ZQ135, est disponible chez <a style=\"color: #1e3a5f; font-weight: 600; text-decoration: none;\" href=\"https:\/\/isbm-blow-molding.com\/fr\/product-category\/injection-blow-molding-machine\/\">Catalogue de machines IBM<\/a> pour la comparaison des sp\u00e9cifications et la mod\u00e9lisation des capacit\u00e9s de production.<\/p>\n<\/section>\n<section style=\"margin: 64px 0 0;\">\n<div style=\"display: flex; align-items: stretch; gap: 0; margin-bottom: 24px;\">\n<div style=\"width: 4px; background: linear-gradient(180deg,#d97706,#f59e0b); border-radius: 2px; flex-shrink: 0;\"><\/div>\n<div style=\"padding: 10px 16px; background: #0f1e35; border-left: none; flex: 1;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 3px;\">FAQ ING\u00c9NIERIE<\/p>\n<h2 id=\"faq\" style=\"font-size: clamp(17px,2.4vw,22px); font-weight: 800; color: #fff; margin: 0; line-height: 1.2;\">IBM tout \u00e9lectrique \u2014 Questions d'ing\u00e9nierie<\/h2>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; gap: 2px;\">\n<div style=\"border: 1px solid #e2e8f0; border-radius: 4px 4px 0 0; overflow: hidden; margin-bottom: 2px;\">\n<div style=\"background: #1e3a5f; padding: 13px 18px; display: flex; align-items: center; gap: 10px;\">\n<p><span style=\"background: #d97706; color: #fff; font-size: 10px; font-weight: 800; padding: 2px 8px; border-radius: 2px; flex-shrink: 0;\">Q 01<\/span><\/p>\n<p style=\"font-size: 14px; font-weight: bold; color: #fff; margin: 0; line-height: 1.3;\">Pourquoi le temps de cycle 20% est-il plus rapide sur ZQ60HE que sur ZQ60 hydraulique avec le m\u00eame format de conteneur\u00a0?<\/p>\n<\/div>\n<div style=\"padding: 18px 20px; background: #fff;\">\n<p style=\"font-size: 15px; color: #374151; margin: 0; line-height: 1.75;\">L'avantage du ZQ60HE en termes de temps de cycle par rapport au ZQ60 hydraulique provient de la diff\u00e9rence fondamentale de vitesse de r\u00e9ponse entre les servomoteurs \u00e9lectriques et les servomoteurs hydrauliques. Dans une machine hydraulique IBM, le v\u00e9rin de serrage n\u00e9cessite un distributeur hydraulique pour inverser le sens du flux d'huile entre l'ouverture et la fermeture. Le temps de r\u00e9ponse du distributeur (g\u00e9n\u00e9ralement de 50 \u00e0 150 ms) auquel s'ajoute le temps d'acc\u00e9l\u00e9ration du fluide hydraulique (l'huile doit passer de l'arr\u00eat \u00e0 la vitesse de d\u00e9placement du v\u00e9rin) engendre un temps total d'ouverture\/fermeture du moule intrins\u00e8quement plus long que l'acc\u00e9l\u00e9ration du servomoteur. Un servomoteur avec boucle de r\u00e9troaction directe par codeur peut acc\u00e9l\u00e9rer de l'arr\u00eat \u00e0 la vitesse de serrage maximale et d\u00e9c\u00e9l\u00e9rer jusqu'\u00e0 l'arr\u00eat en 30 \u00e0 60 ms, soit nettement plus rapidement que le temps d'acc\u00e9l\u00e9ration du distributeur hydraulique et du fluide. Dans l'analyse de cycle IBM, le mouvement d'ouverture\/fermeture du moule se produit deux fois par cycle (ouverture\/fermeture du moule d'injection et ouverture\/fermeture du moule de soufflage), et le mouvement de la table rotative b\u00e9n\u00e9ficie \u00e9galement de la vitesse du servomoteur. La ZQ60HE de Korea Ever-Power affiche une r\u00e9duction du temps de cycle total d'environ 1,5 \u00e0 2 secondes par rapport \u00e0 la ZQ60 hydraulique pour un flacon de gouttes oculaires en PEBD de 30 ml (8,2 s pour la ZQ60HE contre environ 10 s pour la ZQ60 hydraulique), ce qui correspond \u00e0 l'am\u00e9lioration du temps de cycle d'environ 20% mentionn\u00e9e dans les sp\u00e9cifications du produit. Le temps de cycle \u00e0 sec de 2,5 s pour la ZQ60HE contre 4 s pour la ZQ60 hydraulique confirme l'avantage de la servovitesse en termes de d\u00e9placement de la machine, sans incidence sur le temps de traitement du mat\u00e9riau.<\/p>\n<\/div>\n<\/div>\n<div style=\"border: 1px solid #e2e8f0; overflow: hidden; margin-bottom: 2px;\">\n<div style=\"background: #1e3a5f; padding: 13px 18px; display: flex; align-items: center; gap: 10px;\">\n<p><span style=\"background: #d97706; color: #fff; font-size: 10px; font-weight: 800; padding: 2px 8px; border-radius: 2px; flex-shrink: 0;\">Q 02<\/span><\/p>\n<p style=\"font-size: 14px; font-weight: bold; color: #fff; margin: 0; line-height: 1.3;\">La machine ZQ60HE n\u00e9cessite-t-elle une formation diff\u00e9rente pour l'op\u00e9rateur que les machines hydrauliques de la s\u00e9rie ZQ\u00a0?<\/p>\n<\/div>\n<div style=\"padding: 18px 20px; background: #fff;\">\n<p style=\"font-size: 15px; color: #374151; margin: 0; line-height: 1.75;\">La formation des op\u00e9rateurs de la ZQ60HE couvre les m\u00eames principes fondamentaux du processus IBM que celle dispens\u00e9e sur les presses hydrauliques de la s\u00e9rie ZQ\u00a0: sp\u00e9cifications des contenants, s\u00e9lection des mat\u00e9riaux, r\u00e9glage de la temp\u00e9rature du cylindre, contr\u00f4le de la temp\u00e9rature du moule, optimisation des param\u00e8tres de cycle et d\u00e9pannage de la production. La formation sp\u00e9cifique \u00e0 la ZQ60HE inclut des informations suppl\u00e9mentaires sur l'interface des param\u00e8tres d'asservissement\u00a0: les param\u00e8tres de processus de la ZQ60HE comprennent les courbes de vitesse et d'acc\u00e9l\u00e9ration des servomoteurs pour chaque axe de la machine (profil de vitesse d'injection, rampe de vitesse de fermeture, acc\u00e9l\u00e9ration de la table rotative), absentes des param\u00e8tres des presses hydrauliques ZQ. Lors de l'installation de la ZQ60HE, l'ing\u00e9nieur de mise en service de Korea Ever-Power forme les op\u00e9rateurs des clients cor\u00e9ens \u00e0 l'interface des param\u00e8tres d'asservissement, en leur montrant comment ajuster les profils de vitesse des servomoteurs pour diff\u00e9rents formats de contenants et mat\u00e9riaux. L'interface des param\u00e8tres d'asservissement est plus pr\u00e9cise (r\u00e9glages num\u00e9riques contre r\u00e9glages en pourcentage du d\u00e9bit hydraulique) mais aussi plus intuitive une fois que les op\u00e9rateurs comprennent la relation entre les r\u00e9glages de vitesse des servomoteurs et la qualit\u00e9 des contenants. Korea Ever-Power fournit aux clients cor\u00e9ens de la ZQ60HE un manuel d'utilisation couvrant \u00e0 la fois les param\u00e8tres de processus IBM standard et les r\u00e9glages sp\u00e9cifiques des servomoteurs pour tous les formats de contenants du programme de production du client.<\/p>\n<\/div>\n<\/div>\n<div style=\"border: 1px solid #e2e8f0; overflow: hidden; margin-bottom: 2px;\">\n<div style=\"background: #1e3a5f; padding: 13px 18px; display: flex; align-items: center; gap: 10px;\">\n<p><span style=\"background: #d97706; color: #fff; font-size: 10px; font-weight: 800; padding: 2px 8px; border-radius: 2px; flex-shrink: 0;\">Q 03<\/span><\/p>\n<p style=\"font-size: 14px; font-weight: bold; color: #fff; margin: 0; line-height: 1.3;\">Quels mat\u00e9riaux le ZQ60HE peut-il traiter et existe-t-il des mat\u00e9riaux que la motorisation enti\u00e8rement \u00e9lectrique ne peut pas g\u00e9rer\u00a0?<\/p>\n<\/div>\n<div style=\"padding: 18px 20px; background: #fff;\">\n<p style=\"font-size: 15px; color: #374151; margin: 0; line-height: 1.75;\">La ZQ60HE traite tous les mat\u00e9riaux IBM standard sans limitation gr\u00e2ce \u00e0 son syst\u00e8me d'entra\u00eenement enti\u00e8rement \u00e9lectrique\u00a0: PEHD, PEBD, PP, PP RCP, ABS, PS, GPPS, HIPS, EVA, PHA, PLA et PCTG sont tous compatibles avec la ZQ60HE, en utilisant les m\u00eames param\u00e8tres de temp\u00e9rature de fourreau et de moule sp\u00e9cifiques au mat\u00e9riau que la ZQ60 hydraulique. Le syst\u00e8me d'entra\u00eenement servo-command\u00e9 n'impose aucune limitation de viscosit\u00e9, de temp\u00e9rature de traitement ou de pression d'injection qui ne soit d\u00e9j\u00e0 pr\u00e9sente sur la ZQ60 hydraulique\u00a0; la capacit\u00e9 de pression d'injection de la ZQ60HE (contr\u00f4l\u00e9e par servo-couple) est \u00e9gale ou sup\u00e9rieure \u00e0 celle de la ZQ60 hydraulique pour tous les mat\u00e9riaux IBM standard. Les mat\u00e9riaux n\u00e9cessitant un traitement IBM particulier (ABS n\u00e9cessitant un pr\u00e9-s\u00e9chage, PHA\/PLA n\u00e9cessitant des plages de temp\u00e9rature \u00e9troites, EVA n\u00e9cessitant une \u00e2me en PTFE) pr\u00e9sentent les m\u00eames exigences sur la ZQ60HE que sur les machines ZQ hydrauliques. La force de serrage r\u00e9glable du ZQ60HE (400-800 KN servo-command\u00e9e contre 600 KN hydraulique fixe pour le ZQ60) ajoute la possibilit\u00e9 de d\u00e9finir une force de serrage inf\u00e9rieure pour les mat\u00e9riaux flexibles (EVA, LDPE \u00e0 teneur en VA plus \u00e9lev\u00e9e) qui b\u00e9n\u00e9ficient d'une force d'ouverture de serrage r\u00e9duite \u00e0 la station de d\u00e9nudage - un avantage d'optimisation de processus du ZQ60HE par rapport aux machines \u00e0 pression hydraulique fixe pour les applications de mat\u00e9riaux IBM flexibles.<\/p>\n<\/div>\n<\/div>\n<div style=\"border: 1px solid #e2e8f0; overflow: hidden; margin-bottom: 2px;\">\n<div style=\"background: #1e3a5f; padding: 13px 18px; display: flex; align-items: center; gap: 10px;\">\n<p><span style=\"background: #d97706; color: #fff; font-size: 10px; font-weight: 800; padding: 2px 8px; border-radius: 2px; flex-shrink: 0;\">Q 04<\/span><\/p>\n<p style=\"font-size: 14px; font-weight: bold; color: #fff; margin: 0; line-height: 1.3;\">Pour quels formats de conteneurs et applications IBM le ZQ60HE est-il sp\u00e9cifiquement optimis\u00e9\u00a0?<\/p>\n<\/div>\n<div style=\"padding: 18px 20px; background: #fff;\">\n<p style=\"font-size: 15px; color: #374151; margin: 0; line-height: 1.75;\">La ZQ60HE est sp\u00e9cifiquement optimis\u00e9e pour les formats de contenants IBM de petite \u00e0 moyenne capacit\u00e9 (5 \u00e0 200 ml) \u00e0 haut volume de production, o\u00f9 la rapidit\u00e9 du cycle est le principal facteur de rentabilit\u00e9. Les atouts de la ZQ60HE correspondent \u00e0 trois sc\u00e9narios de production IBM sp\u00e9cifiques. Production pharmaceutique IBM \u00e0 haute vitesse en PEBD\u00a0: les flacons de collyre ophtalmiques MFDS cor\u00e9ens (5 \u00e0 15 ml en PEBD, 10 \u00e0 14 cavit\u00e9s) b\u00e9n\u00e9ficient pleinement du gain de temps du cycle 20% de la ZQ60HE. Avec 14 cavit\u00e9s et un temps de cycle \u00e9quivalent \u00e0 30 ml, la ZQ60HE produit environ 115\u00a0000 flacons de collyre par 24 heures, contre 90\u00a0000 pour la ZQ60 hydraulique, soit un gain de production de 25\u00a0000 unit\u00e9s par jour, repr\u00e9sentant 7,5 millions de flacons suppl\u00e9mentaires par an pour l\u2019industrie pharmaceutique cor\u00e9enne. Presse \u00e0 chaud IBM pour cosm\u00e9tiques cor\u00e9ens de petit volume\u00a0: contenants cosm\u00e9tiques de 10 \u00e0 50\u00a0ml en PP RCP ou ABS destin\u00e9s aux marques de K-beauty cor\u00e9ennes. Les d\u00e9lais de livraison des clients cor\u00e9ens sont serr\u00e9s, et la capacit\u00e9 de production accrue de la ZQ60HE permet de r\u00e9duire le d\u00e9lai entre la commande et la livraison, passant d\u2019une planification de plusieurs semaines \u00e0 une livraison en une seule semaine, \u00e0 nombre d\u2019emplacements \u00e9gal. Pot transparent IBM en PS pour compl\u00e9ments alimentaires (100\u00a0ml, exportation vers les \u00c9tats-Unis)\u00a0: l\u2019environnement de production propre de la ZQ60HE (absence d\u2019huile hydraulique, faible niveau sonore, servomoteurs ferm\u00e9s) r\u00e9pond aux normes environnementales am\u00e9ricaines de fabrication de compl\u00e9ments pharmaceutiques, exig\u00e9es par certains clients am\u00e9ricains pour leurs fournisseurs cor\u00e9ens de contenants IBM.<\/p>\n<\/div>\n<\/div>\n<div style=\"border: 1px solid #e2e8f0; overflow: hidden; margin-bottom: 2px;\">\n<div style=\"background: #1e3a5f; padding: 13px 18px; display: flex; align-items: center; gap: 10px;\">\n<p><span style=\"background: #d97706; color: #fff; font-size: 10px; font-weight: 800; padding: 2px 8px; border-radius: 2px; flex-shrink: 0;\">Q 05<\/span><\/p>\n<p style=\"font-size: 14px; font-weight: bold; color: #fff; margin: 0; line-height: 1.3;\">En quoi la r\u00e9p\u00e9tabilit\u00e9 de position de \u00b10,02 mm du ZQ60HE am\u00e9liore-t-elle la qualit\u00e9 des conteneurs IBM par rapport au ZQ60 hydraulique\u00a0?<\/p>\n<\/div>\n<div style=\"padding: 18px 20px; background: #fff;\">\n<p style=\"font-size: 15px; color: #374151; margin: 0; line-height: 1.75;\">La r\u00e9p\u00e9tabilit\u00e9 de position du servocodeur ZQ60HE (\u00b10,02 mm) par rapport \u00e0 celle du capteur de position hydraulique ZQ60 (\u00b10,05-0,10 mm) se traduit par deux avantages sp\u00e9cifiques en termes de qualit\u00e9 des contenants IBM. R\u00e9p\u00e9tabilit\u00e9 du positionnement de la tige de noyau\u00a0: la table rotative ZQ60HE positionne la tige de noyau aux stations d'injection, de soufflage et de d\u00e9moulage avec une r\u00e9p\u00e9tabilit\u00e9 de \u00b10,02 mm par tour, contre \u00b10,05-0,10 mm pour le ZQ60 hydraulique. Une meilleure r\u00e9p\u00e9tabilit\u00e9 du positionnement de la tige de noyau garantit un alignement plus pr\u00e9cis du centre de la tige dans la cavit\u00e9 d'injection, ce qui se traduit par une excentricit\u00e9 de paroi plus constante (\u00e9paisseur de paroi d\u00e9centr\u00e9e) sur l'ensemble des cycles de production. Conform\u00e9ment aux sp\u00e9cifications pharmaceutiques cor\u00e9ennes IBM (excentricit\u00e9 de paroi inf\u00e9rieure \u00e0 \u00b10,05 mm pour un flacon de 10 ml de collyre en PEBD), la r\u00e9p\u00e9tabilit\u00e9 sup\u00e9rieure de la table rotative ZQ60HE offre un avantage en termes de qualit\u00e9 structurelle par rapport au ZQ60 hydraulique, m\u00eame pour les sp\u00e9cifications d'excentricit\u00e9 de paroi les plus strictes. R\u00e9p\u00e9tabilit\u00e9 du profil de vitesse d'injection\u00a0: la r\u00e9gulation servo de la vitesse d'injection du ZQ60HE (position de la vis\u00a0: \u00b10,02\u00a0mm) offre un taux de remplissage plus constant \u00e0 chaque cycle, contrairement \u00e0 la r\u00e9gulation hydraulique du ZQ60 (position de la vis\u00a0: \u00b10,05-0,10\u00a0mm). Il en r\u00e9sulte une variation de poids des pr\u00e9formes inject\u00e9es plus homog\u00e8ne (variation de poids &lt;\u00a0\u00b10,81\u00a0TP3T pour le ZQ60 contre \u00b1\u00a01-21\u00a0TP3T pour le ZQ60 hydraulique, \u00e0 param\u00e8tres de processus \u00e9quivalents). Cette variation de poids plus faible induit une variation de poids plus faible d&#039;une cavit\u00e9 \u00e0 l&#039;autre, et donc une variation d&#039;\u00e9paisseur de paroi plus faible pour toutes les cavit\u00e9s du ZQ60HE.<\/p>\n<\/div>\n<\/div>\n<div style=\"border: 1px solid #e2e8f0; border-radius: 0 0 4px 4px; overflow: hidden; margin-bottom: 64px;\">\n<div style=\"background: #1e3a5f; padding: 13px 18px; display: flex; align-items: center; gap: 10px;\">\n<p><span style=\"background: #d97706; color: #fff; font-size: 10px; font-weight: 800; padding: 2px 8px; border-radius: 2px; flex-shrink: 0;\">Q 06<\/span><\/p>\n<p style=\"font-size: 14px; font-weight: bold; color: #fff; margin: 0; line-height: 1.3;\">Quelle est la diff\u00e9rence de maintenance entre la ZQ60HE et la ZQ60 hydraulique sur une p\u00e9riode de production de 5 ans\u00a0?<\/p>\n<\/div>\n<div style=\"padding: 18px 20px; background: #fff;\">\n<p style=\"font-size: 15px; color: #374151; margin: 0; line-height: 1.75;\">Le profil de maintenance du ZQ60HE sur une p\u00e9riode de production de 5 ans diff\u00e8re de celui du ZQ60 hydraulique sur trois points principaux. Maintenance du syst\u00e8me hydraulique supprim\u00e9e\u00a0: le ZQ60HE ne n\u00e9cessite aucune vidange d\u2019huile hydraulique (g\u00e9n\u00e9ralement requise toutes les 2\u00a0000\u00a0heures sur un IBM hydraulique, soit environ 3\u00a0vidanges par an pour une production quotidienne de 16\u00a0heures), aucun remplacement de filtre hydraulique (4 \u00e0 6\u00a0filtres par an), aucun remplacement de joint hydraulique (les joints des v\u00e9rins d\u2019injection et de soufflage n\u00e9cessitent g\u00e9n\u00e9ralement un remplacement tous les 2 \u00e0 3\u00a0ans sur un IBM hydraulique) et aucune maintenance de la pompe hydraulique. Korea Ever-Power estime que les clients cor\u00e9ens \u00e9conomisent entre 3 et 8\u00a0millions de wons par an en pi\u00e8ces d\u00e9tach\u00e9es et main-d\u2019\u0153uvre pour la maintenance hydraulique en utilisant le ZQ60HE plut\u00f4t que le ZQ60 hydraulique \u00e0 dur\u00e9e de production \u00e9quivalente. Maintenance suppl\u00e9mentaire des servovariateurs\u00a0: les servovariateurs du ZQ60HE (syst\u00e8mes servo industriels Mitsubishi ou Siemens) n\u00e9cessitent un remplacement p\u00e9riodique des condensateurs environ tous les 5\u00a0ans (maintenance pr\u00e9ventive standard pour les servovariateurs industriels en production continue). Les roulements du servomoteur doivent \u00eatre inspect\u00e9s tous les 3 \u00e0 5\u00a0ans selon la dur\u00e9e de production. Ces op\u00e9rations de maintenance sp\u00e9cifiques au servomoteur sont couvertes par le programme de maintenance quinquennal ZQ60HE de Korea Ever-Power, fourni aux clients cor\u00e9ens lors de la mise en service de la machine. Maintenance commune\u00a0: les ZQ60HE et ZQ60 hydrauliques partagent les m\u00eames exigences de maintenance pour la chemise d'usure du cylindre d'injection (remplacement \u00e0 un d\u00e9bit de 15\u00a0000 \u00e0 20\u00a0000\u00a0kg de mati\u00e8re), l'usure des spires de la vis (inspection tous les 12\u00a0mois), le palier de la table rotative (inspection tous les 2\u00a0ans) et le programme d'entretien de repolissage du moule. Korea Ever-Power fournit aux clients cor\u00e9ens de la ZQ60HE un programme de maintenance quinquennal complet pour toutes les cat\u00e9gories d'entretien lors de la livraison de la machine, facilitant ainsi la planification de la maintenance pr\u00e9ventive et l'\u00e9tablissement du budget annuel des co\u00fbts de maintenance par les services comptables cor\u00e9ens.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<div style=\"margin: 0 0 72px; background: #0f1e35; border-radius: 4px; overflow: hidden; position: relative;\">\n<div style=\"height: 4px; background: linear-gradient(90deg,#d97706,#f59e0b,#d97706);\"><\/div>\n<div style=\"position: absolute; right: 0; top: 0; bottom: 0; width: 40%; background: linear-gradient(135deg,transparent 0%,rgba(30,58,95,0.5) 100%); pointer-events: none;\"><\/div>\n<div style=\"position: relative; padding: clamp(32px,5vw,52px) clamp(24px,4vw,48px); text-align: center;\">\n<p style=\"font-size: 9px; font-weight: 800; letter-spacing: 3px; text-transform: uppercase; color: #d97706; margin: 0 0 14px;\">DEMANDE D'INFORMATIONS ZQ60HE \u00b7 COR\u00c9E EVER-POWER<\/p>\n<h2 style=\"font-size: clamp(18px,3vw,28px); font-weight: 900; color: #fff; margin: 0 0 14px; letter-spacing: -0.5px;\">Vous \u00e9valuez les syst\u00e8mes IBM tout \u00e9lectriques pour votre production\u00a0?<\/h2>\n<p style=\"font-size: 15px; color: #94a3b8; max-width: 520px; margin: 0 auto 28px; line-height: 1.65;\">Korea Ever-Power fournit la machine IBM enti\u00e8rement \u00e9lectrique ZQ60HE avec un essai de production avant livraison, une documentation sur la mesure de la consommation d'\u00e9nergie, un soutien \u00e0 la conformit\u00e9 des salles blanches pharmaceutiques et une comparaison compl\u00e8te du retour sur investissement par rapport \u00e0 la ZQ60 hydraulique pour les clients cor\u00e9ens des secteurs pharmaceutique et cosm\u00e9tique utilisant IBM.<\/p>\n<p><a style=\"display: inline-flex; align-items: center; gap: 8px; background: #d97706; color: #fff; padding: 14px 36px; border-radius: 3px; text-decoration: none; font-weight: 800; font-size: 14px; letter-spacing: 0.5px; text-transform: uppercase;\" href=\"https:\/\/isbm-blow-molding.com\/fr\/contact-us\/\">Demande de consultation ZQ60HE <span style=\"font-size: 16px;\">\u2192<\/span><\/a><\/p>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\"><em>\u00c9diteur : Cxm<\/em><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>ALL-ELECTRIC IBM \u00b7 ZQ60HE \u00b7 ZERO HYDRAULIC OIL \u00b7 KOREA EVER-POWER All-Electric IBM Machine Guide: ZQ60HE vs Hydraulic IBM Korea Ever-Power EP-ZQ60HE is the high-speed fully electric injection blow molding machine \u2014 every machine movement driven by servo motors with zero hydraulic oil involvement. The ZQ60HE delivers approximately 20% faster cycle time than equivalent hydraulic [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[24],"tags":[],"class_list":["post-1198","post","type-post","status-publish","format-standard","hentry","category-technical-deep-dive"],"_links":{"self":[{"href":"https:\/\/isbm-blow-molding.com\/fr\/wp-json\/wp\/v2\/posts\/1198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isbm-blow-molding.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isbm-blow-molding.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isbm-blow-molding.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/isbm-blow-molding.com\/fr\/wp-json\/wp\/v2\/comments?post=1198"}],"version-history":[{"count":1,"href":"https:\/\/isbm-blow-molding.com\/fr\/wp-json\/wp\/v2\/posts\/1198\/revisions"}],"predecessor-version":[{"id":1201,"href":"https:\/\/isbm-blow-molding.com\/fr\/wp-json\/wp\/v2\/posts\/1198\/revisions\/1201"}],"wp:attachment":[{"href":"https:\/\/isbm-blow-molding.com\/fr\/wp-json\/wp\/v2\/media?parent=1198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isbm-blow-molding.com\/fr\/wp-json\/wp\/v2\/categories?post=1198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isbm-blow-molding.com\/fr\/wp-json\/wp\/v2\/tags?post=1198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}