{"id":261,"date":"2026-02-10T08:19:58","date_gmt":"2026-02-10T08:19:58","guid":{"rendered":"https:\/\/isbm-blow-molding.com\/?page_id=261"},"modified":"2026-04-24T05:42:12","modified_gmt":"2026-04-24T05:42:12","slug":"about-us","status":"publish","type":"page","link":"https:\/\/isbm-blow-molding.com\/es\/about-us\/","title":{"rendered":"Sobre nosotros"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Header&#8221; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;gcid-e787f6e4-87be-4325-83ae-4380ef468485&#8243; background_image=&#8221;https:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/02\/factory-1.webp&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{%22gcid-e787f6e4-87be-4325-83ae-4380ef468485%22:%91%22background_color%22%93}&#8221;][et_pb_row _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;120px||120px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;02ee1264-944d-44fe-880d-eb7713c98c5a&#8221; header_font=&#8221;Playfair Display|700||on|||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_text_shadow_style=&#8221;preset2&#8243; header_text_shadow_color=&#8221;#000000&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Sobre nosotros<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201db53e328b-fc87-4e7c-84dd-59bd68ef925a\u201d header_2_font=\u201dPlayfair Display|700|||||||\u201d header_2_text_color=\u201d#FFFFFF\u201d width=\u201d50%\u201d header_2_text_shadow_style=\u201dpreset1\u2033 header_2_text_shadow_color=\u201d#000000\u2033 locked=\u201doff\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<h2>Liderando el futuro de la tecnolog\u00eda de moldeo por soplado y estirado por inyecci\u00f3n.<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u201d1\u2033 admin_label=\u201dFeature\u201d _builder_version=\u201d4.21.0\u2033 _module_preset=\u201ddefault\u201d background_enable_color=\u201doff\u201d locked=\u201doff\u201d collapsed=\u201don\u201d global_colors_info=\u201d{}\u201d][et_pb_row column_structure=\u201d1_2,1_2\u2033 _builder_version=\u201d4.21.0\u2033 _module_preset=\u201ddefault\u201d global_colors_info=\u201d{}\u201d][et_pb_column type=\u201d1_2\u2033 _builder_version=\u201d4.21.0\u2033 _module_preset=\u201ddefault\u201d global_colors_info=\u201d{}\u201d][et_pb_image src=\u201dhttps:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/02\/factory-2.webp\u201d alt=\u201dfactory-2\u2033 title_text=\u201dfactory-2\u2033 _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d global_colors_info=\u201d{}\u201d][\/et_pb_image][et_pb_image src=\u201dhttps:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/02\/factory-5.webp\u201d alt=\u201dfactory-5\u2033 title_text=\u201dfactory-5\u2033 align=\u201dright\u201d _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d width=\u201d50%\u201d custom_margin=\u201d-30%|30px|||false|false\u201d box_shadow_style=\u201dpreset7\u2033 box_shadow_color=\u201d#FFFFFF\u201d global_colors_info=\u201d{}\u201d][\/et_pb_image][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d header_3_font=\u201dPlayfair Display|700|||||||\u201d header_3_font_size=\u201d30px\u201d background_color=\u201d#FFFFFF\u201d header_3_text_shadow_style=\u201dpreset2\u2033 global_colors_info=\u201d{}\u201d]<\/p>\n<h3>Valores fundamentales<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d text_font=\u201dPlayfair Display||||||||\u201d text_font_size=\u201d30px\u201d background_color=\u201d#D6D6D6\u2033 custom_margin=\u201d||2px|||\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<ul>\n<li data-start=\"3052\" data-end=\"3064\">\n<p data-start=\"3054\" data-end=\"3064\">Innovaci\u00f3n<\/p>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d text_font=\u201dPlayfair Display||||||||\u201d text_text_color=\u201d#D6D6D6\u2033 text_font_size=\u201d30px\u201d background_color=\u201d#8F8F8F\u201d custom_margin=\u201d||1px|||\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<ul>\n<li data-start=\"3052\" data-end=\"3064\">Calidad<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d text_font=\u201dPlayfair Display||||||||\u201d text_text_color=\u201d#B3B3B3\u2033 text_font_size=\u201d30px\u201d background_color=\u201d#6B6B6B\u201d custom_margin=\u201d||-2px|||\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<ul>\n<li data-start=\"3052\" data-end=\"3064\">\n<p data-start=\"3054\" data-end=\"3064\">Sostenibilidad<\/p>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d text_font=\u201dPlayfair Display||||||||\u201d text_text_color=\u201d#D6D6D6\u2033 text_font_size=\u201d30px\u201d background_color=\u201d#474747\u2033 custom_padding=\u201d7px|||||\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<ul>\n<li data-start=\"3052\" data-end=\"3064\">\n<p data-start=\"3054\" data-end=\"3064\">Satisfacci\u00f3n del cliente<\/p>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u201d1_2\u2033 _builder_version=\u201d4.21.0\u2033 _module_preset=\u201ddefault\u201d global_colors_info=\u201d{}\u201d][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201df346a940-31b1-418a-b7a2-866352e0c5e3\u2033 header_2_font=\u201dPlayfair Display|700|||||||\u201d header_2_text_shadow_style=\u201dpreset1\u2033 locked=\u201doff\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<h2>Nuestra misi\u00f3n: innovaci\u00f3n y excelencia en la tecnolog\u00eda ISBM.<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201db53e328b-fc87-4e7c-84dd-59bd68ef925a\u201d text_font=\u201dUrbanist||||||||\u201d locked=\u201doff\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<p>Korea Ever-Power Injection Stretch Blow Moulding Machine Co., Ltd. es una empresa pionera dedicada a proporcionar m\u00e1quinas ISBM (Injection Stretch Blow Moulding) de alta calidad y eficiencia energ\u00e9tica. Fundada con el objetivo de revolucionar la industria del embalaje, nos especializamos en la fabricaci\u00f3n de m\u00e1quinas fiables y de alto rendimiento que satisfacen las demandas de los mercados globales de embalaje. Nuestra tecnolog\u00eda est\u00e1 dise\u00f1ada para ofrecer a los fabricantes soluciones rentables, energ\u00e9ticamente eficientes y de alta precisi\u00f3n para la producci\u00f3n de una amplia gama de envases de pl\u00e1stico.<\/p>\n<p>[\/et_pb_text][et_pb_image src=\u201dhttps:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/02\/certificatification-1.png\u201d alt=\u201dcertificatification-1\u2033 title_text=\u201dcertificatification-1\u2033 _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d filter_saturate=\u201d0%\u201d global_colors_info=\u201d{}\u201d][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u201d1\u2033 admin_label=\u201dEquipo\u201d _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d background_enable_color=\u201doff\u201d collapsed=\u201don\u201d global_colors_info=\u201d{}\u201d][et_pb_row _builder_version=\u201d4.21.0\u2033 _module_preset=\u201ddefault\u201d global_colors_info=\u201d{}\u201d][et_pb_column type=\u201d4_4\u2033 _builder_version=\u201d4.21.0\u2033 _module_preset=\u201ddefault\u201d global_colors_info=\u201d{}\u201d][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201df346a940-31b1-418a-b7a2-866352e0c5e3\u2033 header_2_font=\u201dPlayfair Display|700|||||||\u201d text_orientation_tablet=\u201dcenter\u201d text_orientation_phone=\u201dcenter\u201d text_orientation_last_edited=\u201don|tablet\u201d header_2_text_shadow_style=\u201dpreset2\u2033 locked=\u201doff\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<h2>\u00bfPor qu\u00e9 elegirnos?<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u201d1_3,1_3,1_3\u2033 _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d global_colors_info=\u201d{}\u201d][et_pb_column type=\u201d1_3\u2033 _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d custom_padding=\u201d20px|20px|20px|20px|true|true\u201d box_shadow_style=\u201dpreset6\u2033 global_colors_info=\u201d{}\u201d][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d header_3_font=\u201dPlayfair Display||||||||\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<h3>Experiencia en el sector y tecnolog\u00eda avanzada<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d text_font=\u201dUrbanist||||||||\u201d text_font_size=\u201d18px\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<p>Con m\u00e1s de 20 a\u00f1os de experiencia, Korea Ever-Power es un proveedor l\u00edder de maquinaria ISBM en Corea del Sur e internacionalmente. Utilizamos la tecnolog\u00eda servoaccionada m\u00e1s avanzada para ofrecer m\u00e1quinas compatibles con los moldes m\u00e1s populares, incluidos los moldes ASB japoneses. Nuestras m\u00e1quinas ofrecen una precisi\u00f3n, fiabilidad y flexibilidad inigualables.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u201d1_3\u2033 _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d custom_padding=\u201d20px|20px|20px|20px|true|true\u201d box_shadow_style=\u201dpreset6\u2033 global_colors_info=\u201d{}\u201d][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d header_3_font=\u201dPlayfair Display||||||||\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<h3>Alcance global, experiencia local.<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d text_font=\u201dUrbanist||||||||\u201d text_font_size=\u201d18px\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<p>Prestamos servicios a clientes en diversas regiones, incluyendo Corea del Sur, Jap\u00f3n, China y el Sudeste Asi\u00e1tico. Nuestro equipo ofrece asistencia y experiencia localizadas para garantizar que cada cliente reciba soluciones personalizadas para sus necesidades de embalaje.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u201d1_3\u2033 _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d custom_padding=\u201d20px|20px|20px|20px|true|true\u201d box_shadow_style=\u201dpreset6\u2033 global_colors_info=\u201d{}\u201d][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d header_3_font=\u201dPlayfair Display||||||||\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<h3>Compromiso con la sostenibilidad<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d text_font=\u201dUrbanist||||||||\u201d text_font_size=\u201d18px\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<p>Nuestras m\u00e1quinas est\u00e1n dise\u00f1adas pensando en la eficiencia energ\u00e9tica, reduciendo el consumo de energ\u00eda hasta en 401 TP3T en comparaci\u00f3n con las m\u00e1quinas tradicionales. Esto est\u00e1 en consonancia con nuestro compromiso con la sostenibilidad y las pr\u00e1cticas de fabricaci\u00f3n respetuosas con el medio ambiente.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u201d1_3,1_3,1_3\u2033 _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d width=\u201d100%\u201d max_width=\u201d100%\u201d custom_padding=\u201d|20px||20px|false|true\u201d global_colors_info=\u201d{}\u201d][et_pb_column type=\u201d1_3\u2033 _builder_version=\u201d4.21.0\u2033 _module_preset=\u201ddefault\u201d global_colors_info=\u201d{}\u201d][et_pb_image src=\u201dhttps:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/02\/One-step-Injection-Stretch-Blowing-Mould-1.webp\u201d alt=\u201dMolde de soplado por inyecci\u00f3n y estiramiento en un solo paso-1\u2033 title_text=\u201dMolde de soplado por inyecci\u00f3n y estiramiento en un solo paso-1\u2033 align_tablet=\u201dcenter\u201d align_phone=\u201dcenter\u201d align_last_edited=\u201don|tablet\u201d _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d box_shadow_style=\u201dpreset6\u2033 global_colors_info=\u201d{}\u201d][\/et_pb_image][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201d74f7a5ae-33d8-4bfe-92c8-11bb14b04f6d\u201d header_3_font=\u201dPlayfair Display||||||||\u201d custom_margin=\u201d||0px||false|false\u201d text_orientation_tablet=\u201dcenter\u201d text_orientation_phone=\u201dcenter\u201d text_orientation_last_edited=\u201don|tablet\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<h3>Molde de inyecci\u00f3n-soplado en un solo paso<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u201d1_3\u2033 _builder_version=\u201d4.21.0\u2033 _module_preset=\u201ddefault\u201d global_colors_info=\u201d{}\u201d][et_pb_image src=\u201dhttps:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/02\/ISBM-2.webp\u201d alt=\u201dISBM-2\u2033 title_text=\u201dISBM-2\u2033 align_tablet=\u201dcenter\u201d align_phone=\u201dcenter\u201d align_last_edited=\u201don|tablet\u201d _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d animation_style=\u201dflip\u201d box_shadow_style=\u201dpreset6\u2033 global_colors_info=\u201d{}\u201d][\/et_pb_image][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201d74f7a5ae-33d8-4bfe-92c8-11bb14b04f6d\u201d header_3_font=\u201dPlayfair Display||||||||\u201d custom_margin=\u201d||0px||false|false\u201d text_orientation_tablet=\u201dcenter\u201d text_orientation_phone=\u201dcenter\u201d text_orientation_last_edited=\u201don|tablet\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<h3>M\u00e1quinas de moldeo por inyecci\u00f3n-estirado-soplado<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u201d1_3\u2033 _builder_version=\u201d4.21.0\u2033 _module_preset=\u201ddefault\u201d global_colors_info=\u201d{}\u201d][et_pb_image src=\u201dhttps:\/\/isbm-blow-molding.com\/wp-content\/uploads\/2026\/02\/injection-stretch-blow-moulding-for-1.webp\u201d alt=\u201dinjection-stretch-blow-moulding-for-1\u2033 title_text=\u201dinjection-stretch-blow-moulding-for-1\u2033 align_tablet=\u201dcenter\u201d align_phone=\u201dcenter\u201d align_last_edited=\u201don|tablet\u201d _builder_version=\u201d4.27.2\u2033 _module_preset=\u201ddefault\u201d animation_style=\u201dslide\u201d box_shadow_style=\u201dpreset6\u2033 global_colors_info=\u201d{}\u201d][\/et_pb_image][et_pb_text _builder_version=\u201d4.27.2\u2033 _module_preset=\u201d74f7a5ae-33d8-4bfe-92c8-11bb14b04f6d\u201d header_3_font=\u201dPlayfair Display||||||||\u201d custom_margin=\u201d||0px||false|false\u201d text_orientation_tablet=\u201dcenter\u201d text_orientation_phone=\u201dcenter\u201d text_orientation_last_edited=\u201don|tablet\u201d global_colors_info=\u201d{}\u201d]<\/p>\n<h3>Pl\u00e1stico y materiales respetuosos con el medio ambiente<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>","protected":false},"excerpt":{"rendered":"<p>Acerca de nosotros: Liderando el futuro de la tecnolog\u00eda de moldeo por inyecci\u00f3n-estirado-soplado. Valores fundamentales: Innovaci\u00f3n, Calidad, Sostenibilidad, Satisfacci\u00f3n del cliente. Nuestra misi\u00f3n: Innovaci\u00f3n y excelencia en la tecnolog\u00eda ISBM. Korea Ever-Power Injection Stretch Blow Moulding Machine Co., Ltd. es una empresa pionera comprometida con el suministro de m\u00e1quinas ISBM (moldeo por inyecci\u00f3n-estirado-soplado) de alta calidad y eficiencia energ\u00e9tica. Fundada con el objetivo de revolucionar [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-261","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/isbm-blow-molding.com\/es\/wp-json\/wp\/v2\/pages\/261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isbm-blow-molding.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/isbm-blow-molding.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/isbm-blow-molding.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/isbm-blow-molding.com\/es\/wp-json\/wp\/v2\/comments?post=261"}],"version-history":[{"count":14,"href":"https:\/\/isbm-blow-molding.com\/es\/wp-json\/wp\/v2\/pages\/261\/revisions"}],"predecessor-version":[{"id":638,"href":"https:\/\/isbm-blow-molding.com\/es\/wp-json\/wp\/v2\/pages\/261\/revisions\/638"}],"wp:attachment":[{"href":"https:\/\/isbm-blow-molding.com\/es\/wp-json\/wp\/v2\/media?parent=261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}